{"id":311800,"date":"2021-10-14T15:56:27","date_gmt":"2021-10-14T18:56:27","guid":{"rendered":"https:\/\/mrnews.com.br\/?p=311800"},"modified":"2021-10-14T15:56:27","modified_gmt":"2021-10-14T18:56:27","slug":"assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/","title":{"rendered":"ASSISTIR Gimnasia La PLATA x Newell&#8217;s Old Boys AO VIVO &#8211; CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE"},"content":{"rendered":"<p style=\"text-align: left;\">A partida entre<strong> Gimnasia La PLATA x Newell&#8217;s Old Boys <\/strong>\u00e9 v\u00e1lida<strong> pela Copa da Liga Profesional ARGENTINA 2021, UMA FASE DO <a href=\"https:\/\/mrnews.com.br\/index.php\/category\/noticias\/esportes\/argentino\/\">CAMPEONATO ARGENTINO<\/a> \u00a0e acontecer\u00e1 hoje, S\u00c1BADO (09\/10) \u00e0s 15:45 hs. O<\/strong> mandante do jogo \u00e9 <strong>o Gimnasia . <\/strong>\u00a0 ALGUNS jogos poder\u00e3o ser vistos ao vivo pela ESPN<b>\/FOX, confira a seguir se este \u00e9 o caso<\/b>.\u00a0O campeonato na s\u00e9rie A est\u00e1 a cada dia mais competitivo e a classifica\u00e7\u00e3o atualizada mostra que os grandes da Argentina est\u00e3o &#8216;bombando&#8217;.<\/p>\n<h2>pr\u00e9-jogo\/ narra\u00e7\u00e3o<\/h2>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/ZOsr2w5hD_I\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nA partida<strong> de hoje<\/strong><strong>\u00a0<\/strong><strong>\u00a0<\/strong>estar\u00e1 dispon\u00edvel para os assinantes da <strong>bet365 <\/strong>e poder\u00e1 ser assistida ao vivo (apenas para apostadores com saldo). Ali\u00e1s, a FOX cancelou alguns canais no Brasil, incluindo o Esporte Interativo e a pr\u00f3pria FOX, mas transmite jogos importantes por seus canais da Turner, SPACE E TNT e n\u00e3o transmitir\u00e1 mais o campeonato para o Brasil. Por outro lado, a <strong>ESPN e a FOX<\/strong> e o grupo Disney, assumiu as transmiss\u00f5es da competi\u00e7\u00e3o para o Brasil e agora, \u00e9 oficialmente o canal do Campeonato Argentino em terras brasileiras.<\/p>\n<p>Fique atento no site do <strong>MRNews<\/strong> para conferir as transmiss\u00f5es dos jogos. Confira <a href=\"https:\/\/mrnews.com.br\/index.php\/category\/noticias\/esportes\/jogos-de-hoje\/\"><strong>jogos de hoje<\/strong><\/a>, e os <a href=\"https:\/\/mrnews.com.br\/index.php\/category\/noticias\/esportes\/jogos-de-amanha\/\"><strong>jogos de amanh\u00e3 na TV<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2>PALPITES<\/h2>\n<p>16.10. 13:30 Sarmiento Junin 1 x 0 Union Santa Fe<br \/>\n16.10. 15:45 Gimnasia L.P.\u00a0 0\u00a0 x 2 Newell&#8217;s Old Boys &#8211;<br \/>\n16.10. 18:00 Lan\u00fas 2 x 1 Banfield<br \/>\n16.10. 20:15 Hurac\u00e1n 0 x 1\u00a0 Boca Juniors<\/p>\n<p>&nbsp;<\/p>\n<h2>odds: CASA 36% EMPATE 34% VISITANTE 30%<\/h2>\n<h2>NARRA\u00c7\u00c3O, PLACAR AO VIVO, Classifica\u00e7\u00e3o E ESCALA\u00c7\u00d5ES<\/h2>\n<p><iframe loading=\"lazy\" style=\"border: 0px #ffffff none;\" src=\"https:\/\/www.flashscore.com.br\/jogo\/U1qstbXB\/#resumo-de-jogo\" width=\"650px\" height=\"600px\" frameborder=\"1\" marginwidth=\"0px\" marginheight=\"0px\" scrolling=\"yes\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<h2>Assista Gimnasia La PLATA x Newell&#8217;s Old Boys ao vivo e gr\u00e1tis na internet (online) S\u00c1BADO (16\/10) \u00e0s 15:45 hs &#8211; CAMPEONATO ARGENTINO<\/h2>\n<p>Todos os jogos os da S\u00e9rie A do campeonato argentino podem ser acompanhadas pela <strong>bet365 <\/strong>. O servi\u00e7o de streaming est\u00e1 dispon\u00edvel em aplicativos para Android e IOS, al\u00e9m de disponibilizar um endere\u00e7o para que o assinante assista ao vivo.<\/p>\n<h4><strong>16.10. 15:45 Gimnasia L.P. x Newell&#8217;s Old Boys &#8211;\u00a0 FOX\/ESPN: N\u00c3O &#8211; AO VIVO AQUI (NARRA\u00c7\u00c3O )<\/strong><\/h4>\n<p>NO PASSADO<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/tU2IgDp-9Vg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>O MRNews alerta que qualquer outro meio de transmiss\u00e3o que n\u00e3o seja a TV aberta e o aplicativo oficial da <strong>FOX<\/strong> n\u00e3o \u00e9 autorizado e pode ser ilegal a distribui\u00e7\u00e3o de imagens. Por isto o site indica apenas o aplicativo para que voc\u00ea assista de forma segura o jogo.<\/p>\n<figure id=\"attachment_257613\" aria-describedby=\"caption-attachment-257613\" style=\"width: 619px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/mrnews.com.br\/index.php\/2020\/12\/02\/assistir-ao-vivo-gimnasia-x-huracan-online-gratis-pelo-campeonato-argentino-2020-21-hoje-04-12\/campeonato-argentino\/\" rel=\"attachment wp-att-257613\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-257613\" src=\"https:\/\/mrnews.com.br\/wp-content\/uploads\/2020\/12\/campeonato-argentino.jpg\" alt=\"campeonato argentino\" width=\"619\" height=\"400\" srcset=\"https:\/\/mrnews.com.br\/wp-content\/uploads\/2020\/12\/campeonato-argentino.jpg 619w, https:\/\/mrnews.com.br\/wp-content\/uploads\/2020\/12\/campeonato-argentino-300x194.jpg 300w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/a><figcaption id=\"caption-attachment-257613\" class=\"wp-caption-text\">campeonato argentino<\/figcaption><\/figure>\n<h1>COPA DA LIGA PROFISSIONAL ARGENTINA<\/h1>\n<p>A Copa da Liga Profissional do Futebol Argentino de 2020 (em espanhol: Copa de la Liga Profesional de F\u00fatbol de AFA 2020),[1][2] tamb\u00e9m conhecida como Copa de la Liga Profesional de 2020 e oficialmente rebatizada como Copa Diego Armando Maradona,[3][4] \u00e9 a primeira edi\u00e7\u00e3o dessa copa do futebol argentino.[1][2] O torneio \u00e9 organizado pela Liga Profissional de Futebol (LPF) da Associa\u00e7\u00e3o do Futebol Argentino (AFA) e conta com a participa\u00e7\u00e3o dos 24 clubes da Superliga Argentina (primeira divis\u00e3o argentina) da temporada de 2019\u201320.[1][2] A competi\u00e7\u00e3o come\u00e7ou no dia 30 de outubro de 2020 e ter\u00e1 seu t\u00e9rmino no dia 24 de janeiro de 2021.[5][6]<\/p>\n<p>Esta copa foi criada como uma &#8220;competi\u00e7\u00e3o tamp\u00e3o&#8221; para cobrir as datas da temporada regular da liga deixada pelo cancelamento da Copa da Superliga Argentina de 2020, esta cancelada por causa da pandemia de COVID-19. Tem como principal objetivo outorgar uma vaga para a Ta\u00e7a Libertadores de 2021, e secundariamente, para a Copa Sul-Americana de 2022.<\/p>\n<h1>CAMPEONATO ARGENTINO DE FUTEBOL 20\/21<\/h1>\n<p>O Campeonato Argentino,\u00a0<b>Primera Divisi\u00f3n<\/b>, conhecido como\u00a0<b>Copa Diego Armando Maradona<\/b>\u00a0a partir da Temporada 2020, \u00e9 a primeira divis\u00e3o da principal competi\u00e7\u00e3o entre clubes de futebol desse pa\u00eds. Entre as temporadas 1990\/1991 e 2011\/2012, o campeonato era dividido em dois torneios por temporada, o Torneo Apertura, disputado na primeira parte do ano, e o Torneo Clausura, disputado na segunda metade, e o campe\u00e3o de cada um desses torneios era considerado campe\u00e3o argentino, ou seja, dois campe\u00f5es por \u00e9poca.<\/p>\n<div class=\"mod\" lang=\"pt-BR\" data-attrid=\"hw:\/collection\/recurring_events:current champion\" data-md=\"1001\" data-hveid=\"CEcQAA\" data-ved=\"2ahUKEwil-62bh7DtAhUYGLkGHbZJBtcQkCkwJHoECEcQAA\">\n<div class=\"Z1hOCe\">\n<div class=\"zloOqf PZPZlf\" data-ved=\"2ahUKEwil-62bh7DtAhUYGLkGHbZJBtcQyxMoADAkegQIRxAB\">\n<div class=\"rVusze\"><strong><span class=\"w8qArf\">Campe\u00e3o atual:\u00a0<\/span><span class=\"LrzXr kno-fv\">Club Atl\u00e9tico Boca Juniors\u00a0<\/span><\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mod\" lang=\"pt-BR\" data-attrid=\"hw:\/collection\/recurring_events:number of teams\" data-md=\"1001\" data-hveid=\"CEoQAA\" data-ved=\"2ahUKEwil-62bh7DtAhUYGLkGHbZJBtcQkCkwJXoECEoQAA\">\n<div class=\"Z1hOCe\">\n<div class=\"zloOqf PZPZlf\" data-ved=\"2ahUKEwil-62bh7DtAhUYGLkGHbZJBtcQyxMoADAlegQIShAB\">\n<div class=\"rVusze\"><strong><span class=\"w8qArf\">N\u00famero de equipes:\u00a0<\/span><span class=\"LrzXr kno-fv\">24<\/span><\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mod\" lang=\"pt-BR\" data-attrid=\"kc:\/organization\/organization:founded\" data-md=\"1001\" data-hveid=\"CEkQAA\" data-ved=\"2ahUKEwil-62bh7DtAhUYGLkGHbZJBtcQkCkwJnoECEkQAA\">\n<div class=\"Z1hOCe\">\n<div class=\"zloOqf PZPZlf\" data-ved=\"2ahUKEwil-62bh7DtAhUYGLkGHbZJBtcQyxMoADAmegQISRAB\">\n<div class=\"rVusze\"><strong><span class=\"w8qArf\">Funda\u00e7\u00e3o:\u00a0<\/span><span class=\"LrzXr kno-fv\">1891<\/span><\/strong><\/div>\n<div><\/div>\n<div>Maiores Campe\u00f5es Argentinos<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"2\">\n<tbody>\n<tr bgcolor=\"#006699\">\n<th width=\"70%\">Clubes<\/th>\n<th width=\"5%\">Campe\u00e3o<\/th>\n<th width=\"5%\">Vice<\/th>\n<th width=\"5%\">Terceiro<\/th>\n<\/tr>\n<tr>\n<td align=\"left\"><b>River Plate<\/b><\/td>\n<td align=\"center\"><b>36<\/b><\/td>\n<td align=\"center\">34<\/td>\n<td align=\"center\">18<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><b>Boca Juniors<\/b><\/td>\n<td align=\"center\"><b>34<\/b><\/td>\n<td align=\"center\">22<\/td>\n<td align=\"center\">19<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><b>Racing Club<\/b><\/td>\n<td align=\"center\"><b>18<\/b><\/td>\n<td align=\"center\">8<\/td>\n<td align=\"center\">12<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><b>Independiente<\/b><\/td>\n<td align=\"center\"><b>16<\/b><\/td>\n<td align=\"center\">16<\/td>\n<td align=\"center\">9<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><b>San Lorenzo<\/b><\/td>\n<td align=\"center\"><b>15<\/b><\/td>\n<td align=\"center\">16<\/td>\n<td align=\"center\">17<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><b>V\u00e9lez Sarsfield<\/b><\/td>\n<td align=\"center\"><b>10<\/b><\/td>\n<td align=\"center\">9<\/td>\n<td align=\"center\">12<\/td>\n<\/tr>\n<tr>\n<td align=\"left\"><b>Alumni<\/b><\/td>\n<td align=\"center\"><b>10<\/b><\/td>\n<td align=\"center\">2<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partida entre Gimnasia La PLATA x Newell&#8217;s Old Boys \u00e9 v\u00e1lida pela Copa da Liga Profesional ARGENTINA 2021, UMA FASE DO CAMPEONATO ARGENTINO \u00a0e acontecer\u00e1 hoje, S\u00c1BADO (09\/10) \u00e0s 15:45 hs. O mandante do jogo \u00e9 o Gimnasia . \u00a0 ALGUNS jogos poder\u00e3o ser vistos ao vivo pela ESPN\/FOX, confira a seguir se este &hellip;<\/p>\n","protected":false},"author":1,"featured_media":279769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11682,3],"tags":[],"class_list":["post-311800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentino","category-esportes1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASSISTIR Gimnasia La PLATA x Newell&#039;s Old Boys AO VIVO - CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASSISTIR Gimnasia La PLATA x Newell&#039;s Old Boys AO VIVO - CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE\" \/>\n<meta property=\"og:description\" content=\"A partida entre Gimnasia La PLATA x Newell&#8217;s Old Boys \u00e9 v\u00e1lida pela Copa da Liga Profesional ARGENTINA 2021, UMA FASE DO CAMPEONATO ARGENTINO \u00a0e acontecer\u00e1 hoje, S\u00c1BADO (09\/10) \u00e0s 15:45 hs. O mandante do jogo \u00e9 o Gimnasia . \u00a0 ALGUNS jogos poder\u00e3o ser vistos ao vivo pela ESPN\/FOX, confira a seguir se este &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T18:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"ASSISTIR Gimnasia La PLATA x Newell&#8217;s Old Boys AO VIVO &#8211; CAMPEONATO ARGENTINO, S\u00c1BADO (16\\\/10), PLACAR ONLINE\",\"datePublished\":\"2021-10-14T18:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/\"},\"wordCount\":702,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Newells-Old-Boys-ESCUDO.jpg\",\"articleSection\":[\"CAMPEONATO ARGENTINO - ASSISTIR AO VIVO, PALPITES, ESCALA\u00c7\u00d5ES\",\"ESPORTES\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/\",\"name\":\"ASSISTIR Gimnasia La PLATA x Newell's Old Boys AO VIVO - CAMPEONATO ARGENTINO, S\u00c1BADO (16\\\/10), PLACAR ONLINE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Newells-Old-Boys-ESCUDO.jpg\",\"datePublished\":\"2021-10-14T18:56:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Newells-Old-Boys-ESCUDO.jpg\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Newells-Old-Boys-ESCUDO.jpg\",\"width\":640,\"height\":364,\"caption\":\"Newell's Old Boys\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2021\\\/10\\\/14\\\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASSISTIR Gimnasia La PLATA x Newell&#8217;s Old Boys AO VIVO &#8211; CAMPEONATO ARGENTINO, S\u00c1BADO (16\\\/10), PLACAR ONLINE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASSISTIR Gimnasia La PLATA x Newell's Old Boys AO VIVO - CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/","og_locale":"pt_BR","og_type":"article","og_title":"ASSISTIR Gimnasia La PLATA x Newell's Old Boys AO VIVO - CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE","og_description":"A partida entre Gimnasia La PLATA x Newell&#8217;s Old Boys \u00e9 v\u00e1lida pela Copa da Liga Profesional ARGENTINA 2021, UMA FASE DO CAMPEONATO ARGENTINO \u00a0e acontecer\u00e1 hoje, S\u00c1BADO (09\/10) \u00e0s 15:45 hs. O mandante do jogo \u00e9 o Gimnasia . \u00a0 ALGUNS jogos poder\u00e3o ser vistos ao vivo pela ESPN\/FOX, confira a seguir se este &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2021-10-14T18:56:27+00:00","og_image":[{"width":640,"height":364,"url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg","type":"image\/jpeg"}],"author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"ASSISTIR Gimnasia La PLATA x Newell&#8217;s Old Boys AO VIVO &#8211; CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE","datePublished":"2021-10-14T18:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/"},"wordCount":702,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"image":{"@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#primaryimage"},"thumbnailUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg","articleSection":["CAMPEONATO ARGENTINO - ASSISTIR AO VIVO, PALPITES, ESCALA\u00c7\u00d5ES","ESPORTES"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/","url":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/","name":"ASSISTIR Gimnasia La PLATA x Newell's Old Boys AO VIVO - CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#primaryimage"},"image":{"@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#primaryimage"},"thumbnailUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg","datePublished":"2021-10-14T18:56:27+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#primaryimage","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg","width":640,"height":364,"caption":"Newell's Old Boys"},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2021\/10\/14\/assistir-gimnasia-la-plata-x-newells-old-boys-ao-vivo-campeonato-argentino-sabado-16-10-placar-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"ASSISTIR Gimnasia La PLATA x Newell&#8217;s Old Boys AO VIVO &#8211; CAMPEONATO ARGENTINO, S\u00c1BADO (16\/10), PLACAR ONLINE"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/04\/Newells-Old-Boys-ESCUDO.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1j72","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/311800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=311800"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/311800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media\/279769"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=311800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=311800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=311800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}