{"id":323174,"date":"2022-02-01T21:12:17","date_gmt":"2022-02-02T00:12:17","guid":{"rendered":"https:\/\/mrnews.com.br\/?p=323174"},"modified":"2022-02-01T21:12:17","modified_gmt":"2022-02-02T00:12:17","slug":"santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/","title":{"rendered":"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)"},"content":{"rendered":"<p>A partida <strong>entre Santa Cruz x Afogados <\/strong>acontece<strong> QUINTA (03\/02) \u00e0s 20:30 hs.<\/strong> O mandante da partida \u00e9 o <strong><a href=\"https:\/\/tvtribunape.com.br\">Santa Cruz<\/a> <\/strong><strong>\u00a0<\/strong>que busca a vit\u00f3ria em seus dom\u00ednios. A partida \u00e1 v\u00e1lida pelo <a href=\"https:\/\/mrnews.com.br\/index.php\/category\/noticias\/esportes\/estaduais\/pernambucano\"><strong>Campeonato Pernambucano<\/strong><\/a> de 2022.\u00a0 <b><em>O <\/em><strong><a href=\"http:\/\/tvtribunape.com.br\/\">Campeonato Pernambucano<\/a><\/strong><\/b> 2022 manter\u00e1 o mesmo formato disputa de 2021 e ser\u00e1 iniciado em 22 de janeiro. Novamente, o estadual ter\u00e1 13 datas, com dez times se enfrentando na primeira fase.<\/p>\n<p>&nbsp;<\/p>\n<p>Como foi decidido pela manuten\u00e7\u00e3o da f\u00f3rmula de disputa, os dez times ir\u00e3o se enfrentam em turno \u00fanico e os dois melhores classificados v\u00e3o direto para a semifinal. As equipes que ficarem dos times do terceiro ao sexto colocado se enfrentar\u00e3o em sistema de mata-mata, para ent\u00e3o decidir os outros dois semifinalistas.<\/p>\n<p>NARRA\u00c7\u00c3O PR\u00c9 E P\u00d3S-JOGO<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/iErczGIAmlo\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>A Federa\u00e7\u00e3o Pernambucana de Futebol (FPF), fez um grande esfor\u00e7o para cobrir &#8216;todos&#8217; os jogos do campeonato e existe uma boa possibilidade das partidas dos times intermedi\u00e1rios (exceto o trio de ferro, Santa Cruz, Sport e N\u00e1utico), serem televisionadas pela Mycujoo TV. J\u00e1 as partidas do trio de ferro ser\u00e3o transmitidas pela Globo Recife e SporTV. O Campeonato Pernambucano de 2021 ser\u00e1 o 22\u00ba consecutivo com transmiss\u00e3o da Rede Globo, com seguidas renova\u00e7\u00f5es desde 2000.\u00a0 Entretanto, o PERNAMBUCANO deve ser o \u00fanico do Nordeste a ser transmitido pela emissora.<\/p>\n<div class=\"wDYxhc\" lang=\"pt-BR\" data-md=\"61\">\n<div class=\"LGOjhe\" role=\"heading\" data-attrid=\"wa:\/description\" aria-level=\"3\" data-hveid=\"CBQQAA\"><span class=\"ILfuVd\"><span class=\"hgKElc\">O\u00a0<b>Campeonato Pernambucano<\/b> ser\u00e1 transmitido em TV aberta pela TV Globo Nordeste em 2022. No pay-per-view, o torneio estar\u00e1 dispon\u00edvel no Premiere. <\/span><\/span>Fique atento no site do <strong>MRNews<\/strong> para conferir as transmiss\u00f5es dos jogos e confira <a href=\"https:\/\/mrnews.com.br\/index.php\/category\/noticias\/esportes\/jogos-de-hoje\/\"><strong>jogos de hoje<\/strong><\/a>, e os <a href=\"https:\/\/mrnews.com.br\/index.php\/category\/noticias\/esportes\/jogos-de-amanha\/\"><strong>jogos de amanh\u00e3 na TV<\/strong><\/a>.<\/div>\n<\/div>\n<div class=\"box no-rounded championship-shortcut\"><\/div>\n<h2>Onde assistir E PALPITES Santa Cruz x Afogados pelo Campeonato Pernambucano QUINTA (03\/02) \u00e0s 20:30 hs<\/h2>\n<p><strong>Todos os jogos<\/strong> dos grandes de Pernambuco ser\u00e3o transmitidos <strong>pelo Pay Per View do Premiere<\/strong>. Este \u00e9 servi\u00e7o de assinatura da Globo.<\/p>\n<p>&nbsp;<\/p>\n<h2>PALPITES 20:30 Santa Cruz 1 x 0 Afogados Rodada 1<\/h2>\n<p>&nbsp;<\/p>\n<div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<h2>CAMPEONATO PERNAMBUCANO DE 2022<\/h2>\n<p><em>O <\/em><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/category\/esportes\/pernambucano\/\">Campeonato Pernambucano<\/a><\/strong><em> 2022 manter\u00e1 o mesmo formato disputa de 2021 e ser\u00e1 iniciado em 22 de janeiro. Novamente, o estadual ter\u00e1 13 datas, com dez times se enfrentando na primeira fase. <\/em><\/p>\n<p>Os representantes dos clubes se encontraram em Conselho Arbitral na Federa\u00e7\u00e3o Pernambucana de Futebol (FPF). Assim, acabou sendo definido pelos representantes das dez equipes participantes da S\u00e9rie A1 do Campeonato Pernambucano 2022 que o formato de disputa seria mantido e que o in\u00edcio da competi\u00e7\u00e3o ser\u00e1 no dia 22 de janeiro.<\/p>\n<p>A reuni\u00e3o foi realizada em Conselho Arbitral com membros da Federa\u00e7\u00e3o Pernambucana de Futebol, na sede da entidade. Os participantes da competi\u00e7\u00e3o ser\u00e3o: <a href=\"http:\/\/revistavigor.com.br\"><strong>N\u00e1utico<\/strong><\/a>, <a href=\"https:\/\/esportsprobr.com.br\">Sport<\/a>, Salgueiro, <strong><a href=\"https:\/\/seried.com.br\/index.php\/category\/times\/santa-cruz\/\">Santa Cruz<\/a><\/strong>, Afogados, Vera Cruz, Retr\u00f4, Sete de Setembro, \u00cdbis e Caruaru City. Os dois \u00faltimos citados conquistaram acesso na temporada atual.<\/p>\n<p>&nbsp;<\/p>\n<p>As quartas de final e as semifinais ser\u00e3o jogos \u00fanicos, com mando de jogo para os melhores classificados na fase de classifica\u00e7\u00e3o e decis\u00e3o em ida e volta. Portanto, o campeonato ter\u00e1 13 datas para ser disputado.<\/p>\n<p>Lembrando que os quatro \u00faltimos colocados da primeira fase do campeonato jogam quadrangular do rebaixamento e os dois melhores escapam do rebaixamento.<\/p>\n<p>Dos seis times que passam de fase, os dois primeiros j\u00e1 se garantem na semifinal. Enquanto que o 3\u00ba enfrenta o 6\u00ba e 4\u00ba enfrenta o 5\u00ba para definir os outros dois semifinalistas. \u00c9 importante lembrar que estes confrontos ser\u00e3o realizados em jogo \u00fanico e o mando ser\u00e1 do time que conseguiu o melhor desempenho na primeira fase.<\/p>\n<p>A semifinal tamb\u00e9m ser\u00e1 em jogo \u00fanico e o mando de campo ser\u00e1 do l\u00edder e vice-l\u00edder da primeira fase. Na final, os confrontos ser\u00e3o de ida e volta, e o clube que tiver feito mais pontos na primeira fase realizar\u00e1 a segunda partida em casa.<\/p>\n<h2><strong>Formato<\/strong><\/h2>\n<ul>\n<li>Primeira fase (Fase de grupos)<\/li>\n<\/ul>\n<p>A primeira fase, todos os clubes se enfrentam em jogos de ida e volta, onde ser\u00e3o classificados os seis melhores. Os quatro piores dever\u00e3o realizar um quadrangular de pontos corridos em tr\u00eas datas, que servir\u00e1 para definir os dois rebaixados para o Campeonato Pernambucano S\u00e9rie A2 de 2023. Os dois primeiros colocados na primeira fase garantem participa\u00e7\u00e3o na semifinal.<\/p>\n<ul>\n<li>Segunda fase (Quartas de Final):<\/li>\n<\/ul>\n<p>Essa fase ser\u00e1 disputada em jogo \u00fanico. O 3\u00ba colocado enfrentar\u00e1 o 6\u00ba e o 4\u00ba jogar\u00e1 contra o 5\u00ba com objetivo de definir os outros dois semifinalistas. O mande de jogo ser\u00e1 dos melhores times e em caso de igualdade, a decis\u00e3o ser\u00e1 feita por meio dos p\u00eanaltis.<\/p>\n<ul>\n<li>Terceira fase (Semifinais):<\/li>\n<\/ul>\n<p>Essa tamb\u00e9m ser\u00e1 disputada em apenas um jogo, que ter\u00e1 mando do l\u00edder e vice-l\u00edder da primeira fase. Se houver empate, a decis\u00e3o ser\u00e1 nos p\u00eanaltis.<\/p>\n<ul>\n<li>Quarta fase (Final):<\/li>\n<\/ul>\n<p>Essa contar\u00e1 com jogos de ida e volta. O time que tiver a melhor campanha no primeiro turno jogar\u00e1 em casa. A defini\u00e7\u00e3o do campe\u00e3o ser\u00e1 por meio de soma da pontua\u00e7\u00e3o nos dois jogos.<\/p>\n<h2><strong>Observa\u00e7\u00f5es<\/strong>:<\/h2>\n<p>Havendo empate nos pontos, o primeiro crit\u00e9rio de avalia\u00e7\u00e3o ser\u00e1 o saldo de gols na fase (sem gol qualificado). Se o empate permanecer nos 180 minutos, a decis\u00e3o ser\u00e1 nos p\u00eanaltis.<\/p>\n<p>Em caso de igualdade em pontos, o primeiro crit\u00e9rio ser\u00e1 o saldo de gols na fase (sem gol qualificado). Persistindo o empate nos 180 minutos, o campe\u00e3o sair\u00e1 nos p\u00eanaltis.<\/p>\n<h2><strong>Os crit\u00e9rios de desempate<\/strong><\/h2>\n<p>Havendo empate na 1\u00aa fase e no quadrangular do rebaixamento ser\u00e3o adotados os seguintes crit\u00e9rios na seguinte ordem:<\/p>\n<ol>\n<li>N\u00famero de vit\u00f3rias<\/li>\n<li>Saldo de gols<\/li>\n<li>Gols marcados<\/li>\n<li>N\u00famero de cart\u00f5es vermelhos<\/li>\n<li>N\u00famero de cart\u00f5es amarelos<\/li>\n<li>Sorteio p\u00fablico<\/li>\n<\/ol>\n<p>J\u00e1 na 2\u00aa, 3\u00aa e 4\u00aa fase, se houver duas equipes com igualdade de pontos ser\u00e3o adotados os seguintes crit\u00e9rios, na ordem a seguir:<\/p>\n<ol>\n<li>Saldo de gols.<\/li>\n<li>Tiros de ponto penal, conforme as Regras do Jogo de Futebol.<\/li>\n<\/ol>\n<\/div>\n<h2>Hist\u00f3ria do Campeonato Pernambucano<\/h2>\n<p>O Campeonato Pernambucano de Futebol \u00e9 a competi\u00e7\u00e3o estadual desse esporte em Pernambuco. \u00c9 realizado ininterruptamente desde 1915. Atualmente \u00e9 organizado pela Federa\u00e7\u00e3o Pernambucana de Futebol.<\/p>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"3\" data-block-id=\"14\">\n<div class=\"content-intertitle\">\n<h2>Lista de campe\u00f5es<\/h2>\n<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"25\" data-block-id=\"15\">\n<ul class=\"content-unordered-list\">\n<li>Sport: 42 vezes<\/li>\n<li>Santa Cruz: 29 vezes<\/li>\n<li>N\u00e1utico: 22 vezes<\/li>\n<li>Am\u00e9rica-PE: 6 vezes<\/li>\n<li>Torre: 3 vezes<\/li>\n<li>Tramways: 2 vezes<\/li>\n<li>Flamengo-PE: 1 vez<\/li>\n<li>Salgueiro: 1 vez<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A partida entre Santa Cruz x Afogados acontece QUINTA (03\/02) \u00e0s 20:30 hs. O mandante da partida \u00e9 o Santa Cruz \u00a0que busca a vit\u00f3ria em seus dom\u00ednios. A partida \u00e1 v\u00e1lida pelo Campeonato Pernambucano de 2022.\u00a0 O Campeonato Pernambucano 2022 manter\u00e1 o mesmo formato disputa de 2021 e ser\u00e1 iniciado em 22 de janeiro. &hellip;<\/p>\n","protected":false},"author":1,"featured_media":287063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3,7682,9774],"tags":[],"class_list":["post-323174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes1","category-pernambucano","category-santa-cruz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)\" \/>\n<meta property=\"og:description\" content=\"A partida entre Santa Cruz x Afogados acontece QUINTA (03\/02) \u00e0s 20:30 hs. O mandante da partida \u00e9 o Santa Cruz \u00a0que busca a vit\u00f3ria em seus dom\u00ednios. A partida \u00e1 v\u00e1lida pelo Campeonato Pernambucano de 2022.\u00a0 O Campeonato Pernambucano 2022 manter\u00e1 o mesmo formato disputa de 2021 e ser\u00e1 iniciado em 22 de janeiro. &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T00:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\\\/02)\",\"datePublished\":\"2022-02-02T00:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/\"},\"wordCount\":1033,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Santa-Cruz-x-Afogados.jpg\",\"articleSection\":[\"ESPORTES\",\"Pernambucano\",\"Santa Cruz\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/\",\"name\":\"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\\\/02)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Santa-Cruz-x-Afogados.jpg\",\"datePublished\":\"2022-02-02T00:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Santa-Cruz-x-Afogados.jpg\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Santa-Cruz-x-Afogados.jpg\",\"width\":500,\"height\":243,\"caption\":\"Santa Cruz x Afogados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2022\\\/02\\\/01\\\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\\\/02)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/","og_locale":"pt_BR","og_type":"article","og_title":"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)","og_description":"A partida entre Santa Cruz x Afogados acontece QUINTA (03\/02) \u00e0s 20:30 hs. O mandante da partida \u00e9 o Santa Cruz \u00a0que busca a vit\u00f3ria em seus dom\u00ednios. A partida \u00e1 v\u00e1lida pelo Campeonato Pernambucano de 2022.\u00a0 O Campeonato Pernambucano 2022 manter\u00e1 o mesmo formato disputa de 2021 e ser\u00e1 iniciado em 22 de janeiro. &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2022-02-02T00:12:17+00:00","og_image":[{"width":500,"height":243,"url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg","type":"image\/jpeg"}],"author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)","datePublished":"2022-02-02T00:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/"},"wordCount":1033,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"image":{"@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#primaryimage"},"thumbnailUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg","articleSection":["ESPORTES","Pernambucano","Santa Cruz"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/","url":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/","name":"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#primaryimage"},"image":{"@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#primaryimage"},"thumbnailUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg","datePublished":"2022-02-02T00:12:17+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#primaryimage","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg","width":500,"height":243,"caption":"Santa Cruz x Afogados"},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2022\/02\/01\/santa-cruz-x-afogados-assistir-ao-vivo-e-palpites-campeonato-pernambucano-de-2022-quinta-03-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Santa Cruz x Afogados: ASSISTIR AO VIVO E PALPITES Campeonato Pernambucano de 2022, QUINTA (03\/02)"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1m4u","amp_enabled":true,"jetpack_featured_media_url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/05\/Santa-Cruz-x-Afogados.jpg","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/323174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=323174"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/323174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media\/287063"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=323174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=323174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=323174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}