{"id":436153,"date":"2025-02-24T18:13:42","date_gmt":"2025-02-24T21:13:42","guid":{"rendered":"https:\/\/mrnews.com.br\/?p=436153"},"modified":"2025-02-24T18:13:42","modified_gmt":"2025-02-24T21:13:42","slug":"palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/","title":{"rendered":"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)"},"content":{"rendered":"<p>O jogo <strong>entre Dourados-MS x Caxias<\/strong><strong>\u00a0<\/strong>marcado para acontecer nesta <strong>HOJE \u00e0s 16 hs <\/strong>(hor\u00e1rio de Bras\u00edlia) PELA edi\u00e7\u00e3o 2025 da Copa do Brasil. A competi\u00e7\u00e3o \u00e9 a mais democr\u00e1tica do Brasil e tem o melhor pr\u00eamio financeiro do pa\u00eds. A partida de hoje tem<strong> Dourados-MS <\/strong>que vai buscar a vit\u00f3ria em seus dom\u00ednios.<\/p>\n<p>Fonte <a href=\"https:\/\/pantanalnoticiasms.com.br\">Site de Not\u00edcias do Dourados-MS<\/a><\/p>\n<h2><strong>Dourados-MS x Caxias: Onde Assistir, Hor\u00e1rio e Escala\u00e7\u00f5es pela Copa do Brasil 2024<\/strong><\/h2>\n<p>A Copa do Brasil 2024 segue a todo vapor, e nesta quarta-feira (26), Dourados-MS e Caxias entram em campo pela primeira fase do torneio. A partida acontece no Est\u00e1dio Dourad\u00e3o, em Dourados-MS, \u00e0s 16h (hor\u00e1rio de Bras\u00edlia). O confronto ser\u00e1 decidido em jogo \u00fanico, e o vencedor avan\u00e7a para a segunda fase.<\/p>\n<h2><strong>Regulamento da Primeira Fase<\/strong><\/h2>\n<p>Nesta etapa da Copa do Brasil, o time visitante n\u00e3o tem mais a vantagem do empate. Se o jogo terminar em igualdade, a vaga ser\u00e1 decidida nos p\u00eanaltis. Dessa forma, tanto Dourados quanto Caxias precisam buscar a vit\u00f3ria para continuar na competi\u00e7\u00e3o nacional.<\/p>\n<h2><strong>Como Chegam as Equipes<\/strong><\/h2>\n<h3><strong>Caxias<\/strong><\/h3>\n<p>O Caxias chega para o duelo embalado pela campanha no Campeonato Ga\u00facho, onde est\u00e1 na fase semifinal. No entanto, vem de uma derrota para o Internacional por 2 a 0 no \u00faltimo domingo. Para esta partida, o t\u00e9cnico Luizinho Vieira ter\u00e1 o retorno do volante Pedro Cuiab\u00e1, que ficou fora do jogo anterior por suspens\u00e3o. Outra novidade pode ser a volta do atacante Welder, recuperado de les\u00e3o.<\/p>\n<h3><strong>Dourados-MS<\/strong><\/h3>\n<p>J\u00e1 o Dourados vem de um empate por 2 a 2 contra o Costa Rica, pela oitava rodada do Campeonato Sul-Mato-Grossense. O time ocupa a quarta posi\u00e7\u00e3o na tabela, com 15 pontos. A equipe sul-mato-grossense aposta em jogadores experientes, como o meia Diego Rosa, ex-Caxias e Juventude, e o atacante Gustavo Sapeka, ex-Esportivo.<\/p>\n<h2><strong>Prov\u00e1veis Escala\u00e7\u00f5es<\/strong><\/h2>\n<h3><strong>Dourados-MS<\/strong><\/h3>\n<ul>\n<li><strong>Goleiro<\/strong>: Felipe<\/li>\n<li><strong>Defensores<\/strong>: L\u00e9o J\u00fanior, Roger, Jo\u00e3o Mariano e Carlinhos<\/li>\n<li><strong>Meio-campo<\/strong>: Abuda, Adson e Diego Rosa<\/li>\n<li><strong>Atacantes<\/strong>: Flaviano, J\u00fanior Prego e Bahia<\/li>\n<li><strong>T\u00e9cnico<\/strong>: Ito Roque<\/li>\n<\/ul>\n<h3><strong>Caxias<\/strong><\/h3>\n<ul>\n<li><strong>Goleiro<\/strong>: Victor Golas<\/li>\n<li><strong>Defensores<\/strong>: Ronei, Lucas Cunha, Alisson e Kelvyn (Marcelo)<\/li>\n<li><strong>Meio-campo<\/strong>: Pedro Cuiab\u00e1 (Mantuan), Vini Guedes e Tomas Bastos<\/li>\n<li><strong>Atacantes<\/strong>: Calyson, Nicholas (Gabriel Lima) e Richard (Welder)<\/li>\n<li><strong>T\u00e9cnico<\/strong>: Luizinho Vieira<\/li>\n<\/ul>\n<h2><strong>Arbitragem<\/strong><\/h2>\n<ul>\n<li><strong>\u00c1rbitro principal<\/strong>: Fabiano Monteiro dos Santos (BA)<\/li>\n<li><strong>Assistentes<\/strong>: Evandro de Melo Lima (BA) e Leandro Matos Feitosa (BA)<\/li>\n<li><strong>Quarto \u00e1rbitro<\/strong>: Everton Moreira Prates (MS)<\/li>\n<\/ul>\n<h2><strong>Onde Assistir Dourados-MS x Caxias?<\/strong><\/h2>\n<p>Infelizmente, n\u00e3o haver\u00e1 transmiss\u00e3o ao vivo do jogo em nenhuma plataforma online ou canal fechado. Os torcedores dever\u00e3o acompanhar a partida atrav\u00e9s de r\u00e1dios e atualiza\u00e7\u00f5es em tempo real nas redes sociais dos clubes.<\/p>\n<h2><strong>Expectativa para o Jogo<\/strong><\/h2>\n<p>O confronto promete ser equilibrado, j\u00e1 que ambas as equipes precisam da vit\u00f3ria para avan\u00e7ar. O Caxias, por ter uma equipe mais experiente e disputar um campeonato estadual mais competitivo, chega como favorito, mas o Dourados joga em casa e busca surpreender.<\/p>\n<p>Acompanhe todas as emo\u00e7\u00f5es da Copa do Brasil e fique por dentro dos pr\u00f3ximos confrontos do torneio!<\/p>\n<h4>An\u00e1lise de Dados<\/h4>\n<p>Para uma an\u00e1lise detalhada dos resultados mais prov\u00e1veis, placares e mais para este jogo acesse <a href=\"https:\/\/palpite.net\">Palpite.net<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O jogo entre Dourados-MS x Caxias\u00a0marcado para acontecer nesta HOJE \u00e0s 16 hs (hor\u00e1rio de Bras\u00edlia) PELA edi\u00e7\u00e3o 2025 da Copa do Brasil. A competi\u00e7\u00e3o \u00e9 a mais democr\u00e1tica do Brasil e tem o melhor pr\u00eamio financeiro do pa\u00eds. A partida de hoje tem Dourados-MS que vai buscar a vit\u00f3ria em seus dom\u00ednios. Fonte Site &hellip;<\/p>\n","protected":false},"author":1,"featured_media":291889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11607,9574,12426,9641,9249,9578,9580,12287,9654,12001,3,4587,9606,9645,9573,9576,12511,10183,9600,9662],"tags":[],"class_list":["post-436153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-america-mg","category-athletico-pr","category-bahia-noticias","category-botafogo","category-campeonato-brasileiro","category-ceara","category-corinthians","category-crb","category-cruzeiro","category-cuiaba","category-esportes1","category-esportes","category-flamengo","category-fluminense","category-fortaleza","category-internacional","category-mercado-da-bola","category-river-plate","category-vasco","category-vitoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)\" \/>\n<meta property=\"og:description\" content=\"O jogo entre Dourados-MS x Caxias\u00a0marcado para acontecer nesta HOJE \u00e0s 16 hs (hor\u00e1rio de Bras\u00edlia) PELA edi\u00e7\u00e3o 2025 da Copa do Brasil. A competi\u00e7\u00e3o \u00e9 a mais democr\u00e1tica do Brasil e tem o melhor pr\u00eamio financeiro do pa\u00eds. A partida de hoje tem Dourados-MS que vai buscar a vit\u00f3ria em seus dom\u00ednios. Fonte Site &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-24T21:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\\\/02)\",\"datePublished\":\"2025-02-24T21:13:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/\"},\"wordCount\":554,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/copa-do-mundo.jpg\",\"articleSection\":[\"Am\u00e9rica-MG\",\"Athletico-PR\",\"Bahia\",\"Botafogo\",\"Campeonato brasileiro\",\"Cear\u00e1\",\"Corinthians\",\"CRB\",\"Cruzeiro\",\"Cuiaba\",\"ESPORTES\",\"Esportes\",\"Flamengo\",\"Fluminense\",\"Fortaleza\",\"Internacional\",\"Mercado da Bola\",\"River Plate\",\"VASCO\",\"Vit\u00f3ria\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/\",\"name\":\"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\\\/02)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/copa-do-mundo.jpg\",\"datePublished\":\"2025-02-24T21:13:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/copa-do-mundo.jpg\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/copa-do-mundo.jpg\",\"width\":720,\"height\":360,\"caption\":\"copa do mundo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/02\\\/24\\\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\\\/02)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/","og_locale":"pt_BR","og_type":"article","og_title":"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)","og_description":"O jogo entre Dourados-MS x Caxias\u00a0marcado para acontecer nesta HOJE \u00e0s 16 hs (hor\u00e1rio de Bras\u00edlia) PELA edi\u00e7\u00e3o 2025 da Copa do Brasil. A competi\u00e7\u00e3o \u00e9 a mais democr\u00e1tica do Brasil e tem o melhor pr\u00eamio financeiro do pa\u00eds. A partida de hoje tem Dourados-MS que vai buscar a vit\u00f3ria em seus dom\u00ednios. Fonte Site &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-02-24T21:13:42+00:00","og_image":[{"width":720,"height":360,"url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg","type":"image\/jpeg"}],"author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)","datePublished":"2025-02-24T21:13:42+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/"},"wordCount":554,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"image":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#primaryimage"},"thumbnailUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg","articleSection":["Am\u00e9rica-MG","Athletico-PR","Bahia","Botafogo","Campeonato brasileiro","Cear\u00e1","Corinthians","CRB","Cruzeiro","Cuiaba","ESPORTES","Esportes","Flamengo","Fluminense","Fortaleza","Internacional","Mercado da Bola","River Plate","VASCO","Vit\u00f3ria"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/","name":"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#primaryimage"},"image":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#primaryimage"},"thumbnailUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg","datePublished":"2025-02-24T21:13:42+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#primaryimage","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg","width":720,"height":360,"caption":"copa do mundo"},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/02\/24\/palpites-dourados-ms-x-caxias-escalacoes-assistir-ao-vivo-copa-do-brasil-2025-hoje-26-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Palpites Dourados-MS x Caxias , Escala\u00e7\u00f5es, Assistir ao vivo COPA DO BRASIL 2025, HOJE (26\/02)"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1PsJ","amp_enabled":true,"jetpack_featured_media_url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2021\/06\/copa-do-mundo.jpg","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/436153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=436153"}],"version-history":[{"count":1,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/436153\/revisions"}],"predecessor-version":[{"id":436154,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/436153\/revisions\/436154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media\/291889"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=436153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=436153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=436153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}