{"id":445520,"date":"2025-06-23T22:09:27","date_gmt":"2025-06-24T01:09:27","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/"},"modified":"2025-06-23T22:09:27","modified_gmt":"2025-06-24T01:09:27","slug":"moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/","title":{"rendered":"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p><strong>O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), disse nesta segunda-feira (23) que a defesa do ex-presidente Jair Bolsonaro poder\u00e1 acompanhar a audi\u00eancia presencial de acarea\u00e7\u00e3o entre Mauro Cid, ex-ajudante de ordens, e o general Braga Netto<\/strong>, que ser\u00e1 realizada nesta ter\u00e7a-feira (26), \u00e0s 10h, no Supremo Tribunal Federal (STF), na a\u00e7\u00e3o penal da trama golpista.<\/p>\n<p>Mais cedo, o advogado Celso Vilardi, representante do ex-presidente, pediu autoriza\u00e7\u00e3o para participar da audi\u00eancia, que ser\u00e1 fechada \u00e0 imprensa e n\u00e3o ser\u00e1 transmitida.<\/p>\n<p><strong>Segundo o ministro, todas as defesas dos r\u00e9us do n\u00facleo 1 da trama golpista podem participar e n\u00e3o \u00e9 necess\u00e1ria autoriza\u00e7\u00e3o pr\u00e9via.\u00a0<\/strong><\/p>\n<p>&#8220;Todas as defesas dos co-r\u00e9us, na presente a\u00e7\u00e3o penal, tem o direito de participar das acarea\u00e7\u00f5es. Julgo prejudicado o pedido&#8221;, decidiu.<\/p>\n<p>A acarea\u00e7\u00e3o entre Cid e Braga Netto foi solicitada pela defesa do general. <strong>Os advogados sustentam que s\u00e3o necess\u00e1rios esclarecimentos sobre as acusa\u00e7\u00f5es de que Braga Netto discutiu o plano Punhal Verde e Amarelo, planejamento golpista para matar autoridades e que teria entregue a Cid dinheiro em uma sacola de vinho.<\/strong><\/p>\n<p>Ambos s\u00e3o r\u00e9us na a\u00e7\u00e3o penal da trama golpista. Cid tamb\u00e9m assinou acordo de dela\u00e7\u00e3o premiada com a Pol\u00edcia Federal (PF) e tamb\u00e9m est\u00e1 na condi\u00e7\u00e3o de delator.<\/p>\n<p>No in\u00edcio deste m\u00eas, <strong>Braga Netto foi interrogado por Alexandre de Moraes e negou ter conhecimento do Punhal Verde Amarelo <\/strong>e de ter repassado a Mauro Cid dinheiro dentro de uma sacola de vinho para que fosse entregue a militares que faziam parte do esquadr\u00e3o de elite do Ex\u00e9rcito, chamados de &#8220;kids-pretos&#8221;.<\/p>\n<p>O general est\u00e1 preso desde dezembro do ano passado sob a acusa\u00e7\u00e3o de obstruir a investiga\u00e7\u00e3o sobre a tentativa de golpe de Estado e tentar obter detalhes dos depoimentos de dela\u00e7\u00e3o de Cid.<\/p>\n<p>Moraes tamb\u00e9m autorizou uma acarea\u00e7\u00e3o entre Anderson Torres, ex-ministro da Justi\u00e7a e ex-secret\u00e1rio de Seguran\u00e7a P\u00fablica do Distrito Federal, e o ex-comandante do Ex\u00e9rcito, general Freire Gomes. <strong>A audi\u00eancia ser\u00e1 realizada, \u00e0s 11h, ap\u00f3s a audi\u00eancia entre Cid e Braga Netto. Torres tamb\u00e9m \u00e9 um dos r\u00e9us do n\u00facleo 1 da trama golpista.\u00a0<\/strong><\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), disse nesta segunda-feira (23) que a defesa do ex-presidente Jair Bolsonaro poder\u00e1 acompanhar a audi\u00eancia presencial de acarea\u00e7\u00e3o entre Mauro Cid, ex-ajudante de ordens, e o general Braga Netto, que ser\u00e1 realizada nesta ter\u00e7a-feira (26), \u00e0s 10h, no Supremo Tribunal Federal (STF), na &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,12225,4],"tags":[],"class_list":["post-445520","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid\" \/>\n<meta property=\"og:description\" content=\"Por EBC, O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), disse nesta segunda-feira (23) que a defesa do ex-presidente Jair Bolsonaro poder\u00e1 acompanhar a audi\u00eancia presencial de acarea\u00e7\u00e3o entre Mauro Cid, ex-ajudante de ordens, e o general Braga Netto, que ser\u00e1 realizada nesta ter\u00e7a-feira (26), \u00e0s 10h, no Supremo Tribunal Federal (STF), na &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T01:09:27+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid\",\"datePublished\":\"2025-06-24T01:09:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/\",\"name\":\"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2025-06-24T01:09:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/06\\\/23\\\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/","og_locale":"pt_BR","og_type":"article","og_title":"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid","og_description":"Por EBC, O ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), disse nesta segunda-feira (23) que a defesa do ex-presidente Jair Bolsonaro poder\u00e1 acompanhar a audi\u00eancia presencial de acarea\u00e7\u00e3o entre Mauro Cid, ex-ajudante de ordens, e o general Braga Netto, que ser\u00e1 realizada nesta ter\u00e7a-feira (26), \u00e0s 10h, no Supremo Tribunal Federal (STF), na &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-06-24T01:09:27+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid","datePublished":"2025-06-24T01:09:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/","name":"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2025-06-24T01:09:27+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/06\/23\/moraes-diz-que-defesa-de-bolsonaro-podera-acompanhar-acareacao-de-cid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Moraes diz que defesa de Bolsonaro poder\u00e1 acompanhar acarea\u00e7\u00e3o de Cid"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1RTO","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/445520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=445520"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/445520\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=445520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=445520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=445520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}