{"id":446219,"date":"2025-07-09T23:19:35","date_gmt":"2025-07-10T02:19:35","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/"},"modified":"2025-07-09T23:19:35","modified_gmt":"2025-07-10T02:19:35","slug":"projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/","title":{"rendered":"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p><strong>A C\u00e2mara dos Deputados aprovou nesta quarta-feira (9) o projeto de lei que pro\u00edbe o uso de animais vertebrados vivos em testes de ingredientes ou de produtos de higiene pessoal, cosm\u00e9ticos e perfumes, inclusive para averiguar seu perigo, sua efic\u00e1cia ou sua seguran\u00e7a.<\/strong> O texto ser\u00e1 enviado \u00e0 san\u00e7\u00e3o presidencial.<\/p>\n<p>A proposta muda a Lei 11.794\/08, que estabelece procedimentos para o uso cient\u00edfico de animais. <strong>A partir da publica\u00e7\u00e3o das mudan\u00e7as, dados obtidos com testes em animais n\u00e3o poder\u00e3o ser utilizados para autorizar a comercializa\u00e7\u00e3o de produtos de higiene pessoal, cosm\u00e9ticos ou perfumes ou seus ingredientes.<\/strong><\/p>\n<p>A exce\u00e7\u00e3o ser\u00e1 para os casos em que forem obtidos para cumprir regulamenta\u00e7\u00e3o n\u00e3o cosm\u00e9tica. Para fazer uso dessa exce\u00e7\u00e3o, as empresas interessadas dever\u00e3o fornecer evid\u00eancias documentais do prop\u00f3sito n\u00e3o cosm\u00e9tico do teste.<\/p>\n<p>O fabricante que tiver a permiss\u00e3o de utilizar novos dados de testes com animais n\u00e3o poder\u00e1 incluir no r\u00f3tulo ou inv\u00f3lucro do produto frases como \u201cn\u00e3o testado em animais\u201d, \u201clivre de crueldade\u201d ou outras express\u00f5es similares.<\/p>\n<p>Para o relator do projeto, deputado Ruy Carneiro (Pode-PB), manter a experimenta\u00e7\u00e3o animal como pr\u00e1tica dominante representaria n\u00e3o apenas uma falha \u00e9tica, mas um retrocesso cient\u00edfico.\u00a0<\/p>\n<blockquote>\n<p>&#8220;M\u00e9todos substitutivos ao uso de animais \u2013 como modelos computacionais, bioimpress\u00e3o 3D de tecidos, organ\u00f3ides e culturas celulares \u2013 v\u00eam se consolidando como ferramentas confi\u00e1veis, \u00e9ticas e muitas vezes mais eficazes&#8221;, afirmou.<\/p>\n<\/blockquote>\n<p>O projeto permite a venda desses produtos e dos ingredientes que os comp\u00f5em quando o teste tenha ocorrido antes da data da entrada em vigor da mudan\u00e7a.<\/p>\n<p><em>*Com informa\u00e7\u00f5es da Ag\u00eancia C\u00e2mara de Not\u00edcias<\/em><\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, A C\u00e2mara dos Deputados aprovou nesta quarta-feira (9) o projeto de lei que pro\u00edbe o uso de animais vertebrados vivos em testes de ingredientes ou de produtos de higiene pessoal, cosm\u00e9ticos e perfumes, inclusive para averiguar seu perigo, sua efic\u00e1cia ou sua seguran\u00e7a. O texto ser\u00e1 enviado \u00e0 san\u00e7\u00e3o presidencial. A proposta muda &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,12225,4],"tags":[],"class_list":["post-446219","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos\" \/>\n<meta property=\"og:description\" content=\"Por EBC, A C\u00e2mara dos Deputados aprovou nesta quarta-feira (9) o projeto de lei que pro\u00edbe o uso de animais vertebrados vivos em testes de ingredientes ou de produtos de higiene pessoal, cosm\u00e9ticos e perfumes, inclusive para averiguar seu perigo, sua efic\u00e1cia ou sua seguran\u00e7a. O texto ser\u00e1 enviado \u00e0 san\u00e7\u00e3o presidencial. A proposta muda &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T02:19:35+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos\",\"datePublished\":\"2025-07-10T02:19:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/\",\"name\":\"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2025-07-10T02:19:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/07\\\/09\\\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos","og_description":"Por EBC, A C\u00e2mara dos Deputados aprovou nesta quarta-feira (9) o projeto de lei que pro\u00edbe o uso de animais vertebrados vivos em testes de ingredientes ou de produtos de higiene pessoal, cosm\u00e9ticos e perfumes, inclusive para averiguar seu perigo, sua efic\u00e1cia ou sua seguran\u00e7a. O texto ser\u00e1 enviado \u00e0 san\u00e7\u00e3o presidencial. A proposta muda &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-07-10T02:19:35+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos","datePublished":"2025-07-10T02:19:35+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/","name":"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2025-07-10T02:19:35+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/07\/09\/projeto-aprovado-na-camara-proibe-uso-de-animais-em-testes-cosmeticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Projeto aprovado na C\u00e2mara pro\u00edbe uso de animais em testes cosm\u00e9ticos"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1S55","amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/446219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=446219"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/446219\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=446219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=446219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=446219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}