{"id":447254,"date":"2025-08-01T18:22:34","date_gmt":"2025-08-01T21:22:34","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/"},"modified":"2025-08-01T18:22:34","modified_gmt":"2025-08-01T21:22:34","slug":"trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/","title":{"rendered":"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p>O <strong>presidente dos Estados Unidos, Donald Trump, informou nesta sexta-feira (1\u00ba) ter\u00a0ordenado\u00a0que dois submarinos nucleares fossem posicionados\u00a0para regi\u00f5es em dire\u00e7\u00e3o \u00e0 R\u00fassia<\/strong>. O <strong>an\u00fancio foi feito\u00a0em resposta \u00e0s declara\u00e7\u00f5es\u00a0do ex-presidente russo Dmitry Medvedev<\/strong>.<\/p>\n<blockquote>\n<p>&#8220;Eu ordenei que dois submarinos nucleares fossem posicionados nas regi\u00f5es apropriadas, apenas para o caso de essas declara\u00e7\u00f5es tolas e inflamat\u00f3rias serem mais do que apenas isso&#8221;, disse Trump em uma m\u00eddia social, ao considerar as manifesta\u00e7\u00f5es de Medvedev\u00a0&#8220;tolas e inflamat\u00f3rias&#8221;.<\/p>\n<\/blockquote>\n<p><strong>Trump e Medvedev, que \u00e9 vice-presidente do Conselho de Seguran\u00e7a da R\u00fassia, trocaram provoca\u00e7\u00f5es nos \u00faltimos dias depois de\u00a0Trump ter estipulado prazo de 10 dias para a R\u00fassia aceitar um cessar-fogo com a Ucr\u00e2nia<\/strong> ou <strong>passaria a taxar pa\u00edses que compram petr\u00f3leo russo, como a \u00cdndia<\/strong>.\u00a0<\/p>\n<p>O <strong>governo de Vladimir Putin estabeleceu seus pr\u00f3prios termos para chegar a um acordo de paz com a Ucr\u00e2nia, e n\u00e3o sinalizou que ir\u00e1 cumprir o prazo de Trump<\/strong>. Em entrevista, Putin disse, sem citar\u00a0Trump, que s\u00e3o necess\u00e1rias novas rodadas de negocia\u00e7\u00e3o\u00a0de paz com a Ucr\u00e2nia para se chegar a um resultado positivo, e que a R\u00fassia aguarda por essas negocia\u00e7\u00f5es.\u00a0<\/p>\n<blockquote>\n<p>&#8220;Para abordar a quest\u00e3o pacificamente, \u00e9 necess\u00e1rio conduzir conversas detalhadas. E n\u00e3o em p\u00fablico, mas com calma, no sil\u00eancio do processo de negocia\u00e7\u00e3o&#8221;, afirmou Putin.<\/p>\n<\/blockquote>\n<p>Antes do an\u00fancio sobre o submarinos, <strong>Medvedev respondeu\u00a0a uma publica\u00e7\u00e3o de Trump,\u00a0que rotulou o\u00a0ex-l\u00edder russo de &#8220;fracassado&#8221;<\/strong>. Medvedev alertou Trump\u00a0para &#8220;cuidado com o que diz&#8221;. Para o ex-presidente russo, a manifesta\u00e7\u00e3o de Trump\u00a0provava que &#8220;a R\u00fassia est\u00e1 fazendo tudo certo e continuar\u00e1 trilhando seu pr\u00f3prio caminho&#8221;.<\/p>\n<blockquote>\n<p>&#8220;E sobre as &#8216;economias mortas&#8217; da \u00cdndia e da R\u00fassia e sua &#8216;entrada em territ\u00f3rio muito perigoso&#8217; \u2014 bem, que ele se lembre de seus filmes favoritos sobre &#8216;mortos-vivos&#8217;, bem como de qu\u00e3o perigosa a lend\u00e1ria &#8216;M\u00e3o Morta&#8217; pode ser&#8221;, escreveu Medvedev.<\/p>\n<\/blockquote>\n<p><strong>M\u00e3o Morta\u00a0refere-se a um sistema de ataque nuclear, montado durante a antiga Uni\u00e3o Sovi\u00e9tica e que ainda estaria em poder da R\u00fassia<\/strong>. O sistema, considerado arma nuclear apocal\u00edptica,\u00a0\u00e9 capaz de disparar um\u00a0arsenal nuclear se o pa\u00eds for atacado e a elimina\u00e7\u00e3o da cadeia de comando for eliminada, segundo a ag\u00eancia de not\u00edcias Russia\u00a0Today.\u00a0<\/p>\n<h2>Petr\u00f3leo<\/h2>\n<p><strong>Trump exigiu\u00a0que a \u00cdndia pare de importar\u00a0petr\u00f3leo russo, o que pode amea\u00e7ar bilh\u00f5es em receitas russas<\/strong>, levar Moscou a retaliar interrompendo um importante oleoduto liderado pelos EUA e potencialmente levar a uma nova crise de abastecimento global.<\/p>\n<p><strong>A \u00cdndia, o terceiro maior importador de petr\u00f3leo do mundo, tornou-se o maior comprador de petr\u00f3leo russo desde 2022<\/strong>, adquirindo at\u00e9 2 milh\u00f5es de barris por dia de petr\u00f3leo, o que representa 2% da oferta global. Outros grandes compradores s\u00e3o a China e a Turquia.<\/p>\n<p><strong>Como retalia\u00e7\u00e3o,\u00a0Kremlin pode fechar\u00a0oleoduto CPC do Cazaquist\u00e3o, usado pelas\u00a0grandes petrol\u00edferas norte-americanas Chevron e Exxon<\/strong>.<\/p>\n<p><strong>Trump tem amea\u00e7ado impor tarifas de at\u00e9 100% aos pa\u00edses que compram petr\u00f3leo russo<\/strong>, a menos que Moscou chegue a um acordo de paz com a Ucr\u00e2nia at\u00e9 o dia 9\u00a0de agosto.\u00a0<\/p>\n<p>De acordo com a ag\u00eancia Reuters,\u00a0refinarias estatais indianas interromperam as compras de petr\u00f3leo russo nesta semana diante\u00a0das\u00a0amea\u00e7as dos Estados Unidos.<\/p>\n<p><em>* Com informa\u00e7\u00f5es da Reuters e da Russia Today\u00a0<\/em><\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, O presidente dos Estados Unidos, Donald Trump, informou nesta sexta-feira (1\u00ba) ter\u00a0ordenado\u00a0que dois submarinos nucleares fossem posicionados\u00a0para regi\u00f5es em dire\u00e7\u00e3o \u00e0 R\u00fassia. O an\u00fancio foi feito\u00a0em resposta \u00e0s declara\u00e7\u00f5es\u00a0do ex-presidente russo Dmitry Medvedev. &#8220;Eu ordenei que dois submarinos nucleares fossem posicionados nas regi\u00f5es apropriadas, apenas para o caso de essas declara\u00e7\u00f5es tolas e &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,12225,4],"tags":[],"class_list":["post-447254","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev\" \/>\n<meta property=\"og:description\" content=\"Por EBC, O presidente dos Estados Unidos, Donald Trump, informou nesta sexta-feira (1\u00ba) ter\u00a0ordenado\u00a0que dois submarinos nucleares fossem posicionados\u00a0para regi\u00f5es em dire\u00e7\u00e3o \u00e0 R\u00fassia. O an\u00fancio foi feito\u00a0em resposta \u00e0s declara\u00e7\u00f5es\u00a0do ex-presidente russo Dmitry Medvedev. &#8220;Eu ordenei que dois submarinos nucleares fossem posicionados nas regi\u00f5es apropriadas, apenas para o caso de essas declara\u00e7\u00f5es tolas e &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T21:22:34+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev\",\"datePublished\":\"2025-08-01T21:22:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/\"},\"wordCount\":607,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/\",\"name\":\"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2025-08-01T21:22:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/01\\\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/","og_locale":"pt_BR","og_type":"article","og_title":"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev","og_description":"Por EBC, O presidente dos Estados Unidos, Donald Trump, informou nesta sexta-feira (1\u00ba) ter\u00a0ordenado\u00a0que dois submarinos nucleares fossem posicionados\u00a0para regi\u00f5es em dire\u00e7\u00e3o \u00e0 R\u00fassia. O an\u00fancio foi feito\u00a0em resposta \u00e0s declara\u00e7\u00f5es\u00a0do ex-presidente russo Dmitry Medvedev. &#8220;Eu ordenei que dois submarinos nucleares fossem posicionados nas regi\u00f5es apropriadas, apenas para o caso de essas declara\u00e7\u00f5es tolas e &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-08-01T21:22:34+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev","datePublished":"2025-08-01T21:22:34+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/"},"wordCount":607,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/","name":"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2025-08-01T21:22:34+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/01\/trump-envia-submarinos-nucleares-para-russia-apos-critica-de-medvedev\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Trump envia submarinos nucleares para R\u00fassia ap\u00f3s cr\u00edtica de Medvedev"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1SlM","amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/447254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=447254"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/447254\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=447254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=447254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=447254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}