{"id":448022,"date":"2025-08-15T13:02:37","date_gmt":"2025-08-15T16:02:37","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/"},"modified":"2025-08-15T13:02:37","modified_gmt":"2025-08-15T16:02:37","slug":"nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/","title":{"rendered":"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p><strong>O plen\u00e1rio do Supremo Tribunal Federal (STF) retomou nesta sexta-feira (15), em Bras\u00edlia, o julgamento do processo em que a deputada federal licenciada Carla Zambelli (foto) (PL-SP) \u00e9 r\u00e9 por porte ilegal de arma de fogo e constrangimento ilegal com emprego de arma de fogo.\u00a0<\/strong><\/p>\n<p>O julgamento foi retomado com o voto do ministro Kassio Nunes Marques, que havia pedido vista (mais tempo para an\u00e1lise) do caso em mar\u00e7o e, at\u00e9 o momento, foi o \u00fanico a votar pela absolvi\u00e7\u00e3o da parlamentar. Ele n\u00e3o divulgou o voto escrito.\u00a0<\/p>\n<p>Em mar\u00e7o, contudo, quando o caso foi a julgamento pela primeira vez, j\u00e1 havia sido alcan\u00e7ada maioria pela condena\u00e7\u00e3o da parlamentar a cinco anos e tr\u00eas meses de pris\u00e3o em regime semiaberto.<\/p>\n<p><strong>Seis ministros votaram pela condena\u00e7\u00e3o: o relator, Gilmar Mendes, Alexandre de Moraes, C\u00e1rmen L\u00facia, Fl\u00e1vio Dino, Cristiano Zanin e Dias Tofolli.\u00a0<\/strong><\/p>\n<p>Todos seguiram o entendimento de Mendes, que votou tamb\u00e9m pela perda do mandato em fun\u00e7\u00e3o da condena\u00e7\u00e3o criminal.\u00a0<\/p>\n<p>O caso \u00e9 julgado no plen\u00e1rio virtual, e os demais ministros t\u00eam at\u00e9 as 23h59 da pr\u00f3xima sexta-feira (22) para votar. Restam os votos dos ministros Lu\u00eds Roberto Barroso, Andr\u00e9 Mendon\u00e7a, Luiz Fux e Edson Fachin.\u00a0<\/p>\n<h2>Relembre o caso<\/h2>\n<p><strong>A a\u00e7\u00e3o penal julgada agora pelo Supremo Tribunal Federal est\u00e1 relacionada ao epis\u00f3dio em que Zambelli sacou uma arma de fogo numa via p\u00fablica de S\u00e3o Paulo e apontou para o jornalista Luan Ara\u00fajo, que perseguiu at\u00e9 uma lanchonete onde ele tentou se proteger.\u00a0<\/strong><\/p>\n<p>O caso ocorreu \u00e0s v\u00e9speras do segundo turno das elei\u00e7\u00f5es de 2022. A persegui\u00e7\u00e3o come\u00e7ou ap\u00f3s Zambelli e Luan trocarem provoca\u00e7\u00f5es durante um ato pol\u00edtico no bairro dos Jardins, em S\u00e3o Paulo.<\/p>\n<p>Em seu voto, Gilmar Mendes afirmou que a rea\u00e7\u00e3o armada diante de ofensas n\u00e3o encontra amparo no Estado Democr\u00e1tico de Direito.<\/p>\n<blockquote>\n<p>&#8220;Ao adentrar no estabelecimento comercial com a arma em punho apontada para Luan, determinando repetidas vezes que o mesmo deitasse no ch\u00e3o, a r\u00e9 claramente for\u00e7ou-o a fazer ato contr\u00e1rio \u00e0 sua vontade, utilizando-se da arma de fogo para subjug\u00e1-lo, mediante grave amea\u00e7a, restringindo sua liberdade momentaneamente&#8221;, afirmou o relator.\u00a0<\/p>\n<\/blockquote>\n<h2>Segunda condena\u00e7\u00e3o\u00a0<\/h2>\n<p>Caso confirmada, essa ser\u00e1 a segunda condena\u00e7\u00e3o de Carla Zambelli pelo STF, ap\u00f3s ela ter sido condenada, em maio, a 10 anos de pris\u00e3o pela invas\u00e3o aos sistemas eletr\u00f4nicos do Conselho Nacional de Justi\u00e7a (CNJ).\u00a0<\/p>\n<p>Antes de ser presa, contudo, Zambelli fugiu para a It\u00e1lia, pa\u00eds do qual tamb\u00e9m possui cidadania. No fim de julho, ela foi localizada e presa pelas autoridades italianas, depois de ter sido inclu\u00edda na difus\u00e3o vermelha da Interpol.<\/p>\n<p>Em seguida, a Justi\u00e7a italiana decidiu mant\u00ea-la presa ap\u00f3s ela ter sido apresentada a um juiz, procedimento similar \u00e0 audi\u00eancia de cust\u00f3dia realizada no Brasil.\u00a0<\/p>\n<p>Ap\u00f3s a fuga para a It\u00e1lia, o governo brasileiro solicitou a extradi\u00e7\u00e3o da deputada para o Brasil. N\u00e3o h\u00e1 prazo para decis\u00e3o final sobre a extradi\u00e7\u00e3o, que ser\u00e1 avaliada pela justi\u00e7a italiana.\u00a0<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, O plen\u00e1rio do Supremo Tribunal Federal (STF) retomou nesta sexta-feira (15), em Bras\u00edlia, o julgamento do processo em que a deputada federal licenciada Carla Zambelli (foto) (PL-SP) \u00e9 r\u00e9 por porte ilegal de arma de fogo e constrangimento ilegal com emprego de arma de fogo.\u00a0 O julgamento foi retomado com o voto do &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,12225,4],"tags":[],"class_list":["post-448022","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli\" \/>\n<meta property=\"og:description\" content=\"Por EBC, O plen\u00e1rio do Supremo Tribunal Federal (STF) retomou nesta sexta-feira (15), em Bras\u00edlia, o julgamento do processo em que a deputada federal licenciada Carla Zambelli (foto) (PL-SP) \u00e9 r\u00e9 por porte ilegal de arma de fogo e constrangimento ilegal com emprego de arma de fogo.\u00a0 O julgamento foi retomado com o voto do &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T16:02:37+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli\",\"datePublished\":\"2025-08-15T16:02:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/\",\"name\":\"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2025-08-15T16:02:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/08\\\/15\\\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/","og_locale":"pt_BR","og_type":"article","og_title":"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli","og_description":"Por EBC, O plen\u00e1rio do Supremo Tribunal Federal (STF) retomou nesta sexta-feira (15), em Bras\u00edlia, o julgamento do processo em que a deputada federal licenciada Carla Zambelli (foto) (PL-SP) \u00e9 r\u00e9 por porte ilegal de arma de fogo e constrangimento ilegal com emprego de arma de fogo.\u00a0 O julgamento foi retomado com o voto do &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-08-15T16:02:37+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli","datePublished":"2025-08-15T16:02:37+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/","name":"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2025-08-15T16:02:37+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/08\/15\/nunes-vota-por-absolvicao-mas-maioria-do-stf-condena-carla-zambelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Nunes vota por absolvi\u00e7\u00e3o, mas maioria do STF condena Carla Zambelli"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1Sya","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/448022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=448022"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/448022\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=448022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=448022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=448022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}