{"id":450342,"date":"2025-10-05T08:55:47","date_gmt":"2025-10-05T11:55:47","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/"},"modified":"2025-10-05T08:55:47","modified_gmt":"2025-10-05T11:55:47","slug":"procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/","title":{"rendered":"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A proximidade do Dia das Crian\u00e7as deixa o movimento o com\u00e9rcio mais efervescente com o aumento do consumo de artigos de lazer infantil e os consumidores que v\u00e3o presentear no pr\u00f3ximo 12 de outubro, Dia das Crian\u00e7as, precisam ficar atentos aos cuidados necess\u00e1rios na hora de adquirir os produtos que se destinam a esse p\u00fablico. Para ajudar em uma compra segura, o Procon-JP est\u00e1 divulgando dicas e orienta\u00e7\u00f5es.<\/p>\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><\/figure>\n<figure class=\"wp-block-image size-large\"><\/figure>\n<\/figure>\n<p>O primeiro conselho \u00e9 verificar se o artigo obedece \u00e0s especifica\u00e7\u00f5es t\u00e9cnicas de finalidade e de seguran\u00e7a atrav\u00e9s do Selo de Qualidade do Instituto Nacional de Metrologia, Qualidade e Tecnologia (Inmetro), \u00f3rg\u00e3o respons\u00e1vel pela seguran\u00e7a de produtos de lazer infantil.<\/p>\n<p>O secret\u00e1rio do Procon-JP, Junior Pires, alerta que essa deve ser a primeira coisa a ser verificada pelo consumidor. \u201c\u00c9 atrav\u00e9s do Selo de Qualidade do Inmetro que a pessoa vai ter certeza de que o brinquedo pode ser usado com seguran\u00e7a\u201d.<strong\/><\/p>\n<p><strong>Acidentes<\/strong> \u2013 Outra dica do Procon-JP \u00e9 quanto aos pais ficarem alertas \u00e0s informa\u00e7\u00f5es contidas nas embalagens dos produtos, como a destina\u00e7\u00e3o da faixa et\u00e1ria porque esse tipo de detalhe \u00e9 importante para evitar acidentes. \u201cImagine uma crian\u00e7a pequena brincar com pe\u00e7as diminutas e levar \u00e0 boca e engolir. \u00c9 desse tipo de problema que estamos falando\u201d, pontua o secret\u00e1rio.<\/p>\n<p><strong>Montagem<\/strong> \u2013 Mais uma orienta\u00e7\u00e3o do Procon-JP \u00e9 que o consumidor deve ficar atento quanto \u00e0s instru\u00e7\u00f5es de montagem e de uso e se essas informa\u00e7\u00f5es est\u00e3o escritas em Portugu\u00eas de forma clara e compreens\u00edvel, ainda que o produto tenha sido fabricado no exterior.<\/p>\n<p><strong>Validade<\/strong> \u2013 Junior Pires acrescenta que a data de validade tamb\u00e9m deve ser verificada e que todo tipo de produto deve ter o prazo de uso exposto na embalagem e os brinquedos n\u00e3o s\u00e3o exce\u00e7\u00e3o. \u201cQualquer material vai se danificando com o passar do tempo\u201d.<\/p>\n<p><strong>\u00daltima hora<\/strong> \u2013 Outra dica \u00e9 quanto a n\u00e3o deixar as compras para a \u00faltima hora para n\u00e3o aumentar o risco de escolhas erradas ou de adquirir produtos com algum defeito. \u201cO consumidor deve lembrar que as lojas f\u00edsicas n\u00e3o t\u00eam a obriga\u00e7\u00e3o de trocar o artigo, a n\u00e3o ser que haja algum defeito\u201d, pontua Pires.<\/p>\n<p><strong>Compras online \u2013 <\/strong>Para as compras online, as regras de seguran\u00e7a s\u00e3o as mesmas que no com\u00e9rcio f\u00edsico, mas existe o chamado \u2018direito de arrependimento\u2019, com o produto podendo ser devolvido no prazo de sete dias a contar da data do recebimento se o consumidor encontrar algum defeito ou mesmo se n\u00e3o gostar do artigo.<\/p>\n<p>\u201cPara quem preferir a troca do produto, pode faz\u00ea-lo nesse prazo, assim como tem direito \u00e0 escolha do reembolso do valor pago com a devida corre\u00e7\u00e3o monet\u00e1ria\u201d, esclarece o secret\u00e1rio do Procon_JP.<\/p>\n<p><strong>Apreens\u00f5es<\/strong> \u2013 Ele informa, ainda, que a fiscaliza\u00e7\u00e3o deste ano j\u00e1 apreendeu mais de 3,3 mil artigos de lazer infantil em diversas lojas da Capital e que a inspe\u00e7\u00e3o a esses estabelecimentos s\u00f3 vai terminar na v\u00e9spera do Dia das Crian\u00e7as, para garantir mais seguran\u00e7as para quem est\u00e1 comprando esse tipo de produto. \u201cA maior parte das apreens\u00f5es foi de produtos sem o Selo de Qualidade do Inmetro, al\u00e9m da falta das datas de fabrica\u00e7\u00e3o, de validade e de informa\u00e7\u00f5es em Portugu\u00eas\u201d.<\/p>\n<p><strong>Atendimentos do Procon-JP<\/strong><\/p>\n<p>Sede: Avenida Pedro I, 382, Tambi\u00e1, das 8h \u00e0s 17h<\/p>\n<p>Telefone: 0800 083 2015<\/p>\n<p>Procon-JP na sua m\u00e3o: (83) 98665-0179<\/p>\n<p>WhatsApp Transporte p\u00fablico: (83) 98873-9976<\/p>\n<p>Instagram: @procon_jp<\/p>\n<p>Site: procon.joaopessoa.pb.gov.br<\/p>\n<p>\u00a0Procon-JP Digital: totens instalados nos shoppings Mangabeira, Mana\u00edra, Tambi\u00e1 e Parahyba Mall<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A proximidade do Dia das Crian\u00e7as deixa o movimento o com\u00e9rcio mais efervescente com o aumento do consumo de artigos de lazer infantil e os consumidores que v\u00e3o presentear no pr\u00f3ximo 12 de outubro, Dia das Crian\u00e7as, precisam ficar atentos aos cuidados necess\u00e1rios na hora de adquirir os produtos que se destinam a esse p\u00fablico. &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-450342","post","type-post","status-publish","format-standard","hentry","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as\" \/>\n<meta property=\"og:description\" content=\"A proximidade do Dia das Crian\u00e7as deixa o movimento o com\u00e9rcio mais efervescente com o aumento do consumo de artigos de lazer infantil e os consumidores que v\u00e3o presentear no pr\u00f3ximo 12 de outubro, Dia das Crian\u00e7as, precisam ficar atentos aos cuidados necess\u00e1rios na hora de adquirir os produtos que se destinam a esse p\u00fablico. &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-05T11:55:47+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as\",\"datePublished\":\"2025-10-05T11:55:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/\"},\"wordCount\":632,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/\",\"name\":\"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2025-10-05T11:55:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/10\\\/05\\\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/","og_locale":"pt_BR","og_type":"article","og_title":"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as","og_description":"A proximidade do Dia das Crian\u00e7as deixa o movimento o com\u00e9rcio mais efervescente com o aumento do consumo de artigos de lazer infantil e os consumidores que v\u00e3o presentear no pr\u00f3ximo 12 de outubro, Dia das Crian\u00e7as, precisam ficar atentos aos cuidados necess\u00e1rios na hora de adquirir os produtos que se destinam a esse p\u00fablico. &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-10-05T11:55:47+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as","datePublished":"2025-10-05T11:55:47+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/"},"wordCount":632,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/","name":"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2025-10-05T11:55:47+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/10\/05\/procon-jp-da-orientacoes-ao-consumidor-para-compra-segura-dos-presentes-para-o-dia-das-criancas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Procon-JP d\u00e1 orienta\u00e7\u00f5es ao consumidor para compra segura dos presentes para o Dia das Crian\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1T9A","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/450342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=450342"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/450342\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=450342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=450342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=450342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}