{"id":453877,"date":"2025-12-27T10:32:28","date_gmt":"2025-12-27T13:32:28","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/"},"modified":"2025-12-27T10:32:28","modified_gmt":"2025-12-27T13:32:28","slug":"brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/","title":{"rendered":"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p>O m\u00eas de dezembro \u00e9 dedicado \u00e0 campanha de conscientiza\u00e7\u00e3o Dezembro Verde, para lembrar da import\u00e2ncia do cuidado respons\u00e1vel com animais dom\u00e9sticos. A data n\u00e3o \u00e9 aleat\u00f3ria, pois o per\u00edodo de festas \u00e9 considerado o de maior incid\u00eancia de abandonos, al\u00e9m de ser de maior risco para fugas, em raz\u00e3o de maior tempo longe dos humanos de refer\u00eancia e com mais fatores de estresse, como a solta de fogos.<\/p>\n<p><strong>A campanha refor\u00e7a a necessidade de medidas paliativas para o desconforto e a seguran\u00e7a dos animais.<\/strong> A estimativa, est\u00e1vel desde o come\u00e7o da d\u00e9cada, \u00e9 de 30 milh\u00f5es de c\u00e3es, gatos e outras esp\u00e9cies dom\u00e9sticas abandonados.\u00a0<\/p>\n<p>\u201cH\u00e1 constantes progressos na rela\u00e7\u00e3o estabelecida entre pessoas e pets, com intera\u00e7\u00f5es cada vez mais pr\u00f3ximas, intensas e emocionais. Termos como \u2018posse\u2019 e \u2018propriet\u00e1rio\u2019 j\u00e1 n\u00e3o s\u00e3o mais apropriados. Ser respons\u00e1vel por um animal de estima\u00e7\u00e3o e conviver com ele exige que se ofere\u00e7a todas as suas necessidades, tanto f\u00edsicas quanto emocionais\u201d, explica a presidente da Comiss\u00e3o T\u00e9cnica de Bem-Estar Animal do Conselho Regional de Medicina Veterin\u00e1ria do Estado de S\u00e3o Paulo (CRMV-SP), Daniela Ramos.\u00a0<\/p>\n<p>O conselho destaca a import\u00e2ncia da orienta\u00e7\u00e3o de tutores e de servi\u00e7os em busca de melhores condi\u00e7\u00f5es para o bem-estar animal. Uma das quest\u00f5es fundamentais \u00e9 a conscientiza\u00e7\u00e3o da necessidade de planejamento e adequa\u00e7\u00e3o de rotinas. <strong>\u00c9 comum os animais dom\u00e9sticos viverem mais de 10 anos, e seu cuidado em per\u00edodos excepcionais, como as f\u00e9rias, \u00e9 importante para seu desenvolvimento e conforto.<\/strong> Al\u00e9m das necessidades fisiol\u00f3gicas, o bem estar emocional, como a sensa\u00e7\u00e3o de aus\u00eancia de cuidadores, tamb\u00e9m \u00e9 destacado pelo conselho. Uma solu\u00e7\u00e3o, aponta, \u00e9 acostumar os animais com outras pessoas ou lugares de refer\u00eancia, para que a aus\u00eancia dos tutores seja menos sentida.<\/p>\n<p><strong>&#8220;Muitos casos de abandono poderiam ser evitados se, antes da ado\u00e7\u00e3o, as pessoas refletissem sobre quest\u00f5es pr\u00e1ticas como o que fazer com o animal em caso de mudan\u00e7a? Quem cuidar\u00e1 dele durante uma viagem?&#8221;, destaca Daniela Ramos.<\/strong>\u00a0<\/p>\n<p>\u201cAproveite momentos em que voc\u00ea tem mais tempo em casa, como as f\u00e9rias, para refletir sobre a ado\u00e7\u00e3o. Nenhum animal chega pronto para a conviv\u00eancia conosco. \u00c9 preciso ensin\u00e1-lo e gui\u00e1-lo para uma vida em harmonia com a fam\u00edlia. O respons\u00e1vel e todos os membros da casa t\u00eam papel fundamental nesse processo\u201d, complementa a profissional.<\/p>\n<h2>Abandono \u00e9 crime<\/h2>\n<p>A Secretaria Municipal da Sa\u00fade de S\u00e3o Paulo lembra que o abandono de animais \u00e9 considerado crime, conforme a Lei 9.605\/1998, e que notifica\u00e7\u00f5es devem ser feitas aos \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica, por meio da Delegacia Eletr\u00f4nica de Prote\u00e7\u00e3o Animal\u00a0e o\u00a0 Disque Den\u00fancia Animal, no 0800-600-6428.\u00a0<\/p>\n<p><strong>O abandono de animais pode levar a pena de at\u00e9 1 ano de pris\u00e3o, o que \u00e9 agravado se houver ind\u00edcios de maus tratos ou risco para a sa\u00fade do animal.<\/strong><\/p>\n<p>Na capital paulista animais abandonados s\u00e3o recolhidos pela Divis\u00e3o de Vigil\u00e2ncia de Zoonoses (DVZ), da Coordenadoria de Vigil\u00e2ncia em Sa\u00fade (Covisa), o \u00f3rg\u00e3o de sa\u00fade p\u00fablica respons\u00e1vel pela remo\u00e7\u00e3o de c\u00e3es e gatos sem dono, encontrados soltos em vias e logradouros p\u00fablicos, em algumas situa\u00e7\u00f5es, como casos comprovados de agress\u00e3o, invas\u00e3o comprovada a institui\u00e7\u00f5es p\u00fablicas, locais em situa\u00e7\u00e3o de risco \u00e0 sa\u00fade p\u00fablica ou animais em estado de sofrimento, sendo priorizadas as situa\u00e7\u00f5es em que existe risco \u00e0 sa\u00fade humana.<\/p>\n<h2>Santa Catarina<\/h2>\n<p>Alguns estados tornam o m\u00eas de dezembro como o momento estrat\u00e9gico para debater o tema. \u00c9 o caso de Santa Catarina, que organizou a campanha <em>N\u00e3o abandone o amor<\/em>, com publicidade nas ruas e uma campanha multim\u00eddia, que vai at\u00e9 janeiro.\u00a0\u00a0\u00a0<\/p>\n<blockquote>\n<p>\u201cA ideia da campanha surgiu a partir de uma constata\u00e7\u00e3o, baseada em dados, de que, principalmente nesta \u00e9poca de final de ano e alta temporada, aumentam os casos de ado\u00e7\u00e3o, com as pessoas mais sensibilizadas\u201d, disse a diretora estadual do Bem-Estar Animal, Fabr\u00edcia Rosa Costa.<\/p>\n<\/blockquote>\n<p>No entanto, ela lembra que, ao mesmo tempo, aumentam os casos de abandono de pets, quando as fam\u00edlias saem de f\u00e9rias ou se mudam, e n\u00e3o tendo como quem deixar ou doar, acabam abandonando os animais \u00e0 pr\u00f3pria sorte.\u00a0<\/p>\n<p>\u201cEssa realidade precisa mudar, afinal pet n\u00e3o \u00e9 brinquedo e s\u00e3o seres sencientes [capazes de sentir sensa\u00e7\u00f5es e sentimentos de forma consciente], que sentem fome, medo, tristeza, frio, calor e desamparo nessas situa\u00e7\u00f5es\u201d, afirma.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, O m\u00eas de dezembro \u00e9 dedicado \u00e0 campanha de conscientiza\u00e7\u00e3o Dezembro Verde, para lembrar da import\u00e2ncia do cuidado respons\u00e1vel com animais dom\u00e9sticos. A data n\u00e3o \u00e9 aleat\u00f3ria, pois o per\u00edodo de festas \u00e9 considerado o de maior incid\u00eancia de abandonos, al\u00e9m de ser de maior risco para fugas, em raz\u00e3o de maior tempo &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,12225,4],"tags":[],"class_list":["post-453877","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados\" \/>\n<meta property=\"og:description\" content=\"Por EBC, O m\u00eas de dezembro \u00e9 dedicado \u00e0 campanha de conscientiza\u00e7\u00e3o Dezembro Verde, para lembrar da import\u00e2ncia do cuidado respons\u00e1vel com animais dom\u00e9sticos. A data n\u00e3o \u00e9 aleat\u00f3ria, pois o per\u00edodo de festas \u00e9 considerado o de maior incid\u00eancia de abandonos, al\u00e9m de ser de maior risco para fugas, em raz\u00e3o de maior tempo &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-27T13:32:28+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados\",\"datePublished\":\"2025-12-27T13:32:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/\"},\"wordCount\":804,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/\",\"name\":\"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2025-12-27T13:32:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2025\\\/12\\\/27\\\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/","og_locale":"pt_BR","og_type":"article","og_title":"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados","og_description":"Por EBC, O m\u00eas de dezembro \u00e9 dedicado \u00e0 campanha de conscientiza\u00e7\u00e3o Dezembro Verde, para lembrar da import\u00e2ncia do cuidado respons\u00e1vel com animais dom\u00e9sticos. A data n\u00e3o \u00e9 aleat\u00f3ria, pois o per\u00edodo de festas \u00e9 considerado o de maior incid\u00eancia de abandonos, al\u00e9m de ser de maior risco para fugas, em raz\u00e3o de maior tempo &hellip;","og_url":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2025-12-27T13:32:28+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados","datePublished":"2025-12-27T13:32:28+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/"},"wordCount":804,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/","url":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/","name":"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2025-12-27T13:32:28+00:00","breadcrumb":{"@id":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mrnews.com.br\/index.php\/2025\/12\/27\/brasil-tem-cerca-de-30-milhoes-de-animais-domesticos-abandonados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Brasil tem cerca de 30 milh\u00f5es de animais dom\u00e9sticos abandonados"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1U4B","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/453877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=453877"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/453877\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=453877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=453877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=453877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}