{"id":458154,"date":"2026-03-29T00:38:01","date_gmt":"2026-03-29T03:38:01","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2026\/03\/29\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\/"},"modified":"2026-03-30T08:10:24","modified_gmt":"2026-03-30T11:10:24","slug":"populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2026\/03\/29\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\/","title":{"rendered":"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O plantio do Bosque da COP15, neste s\u00e1bado (28), no Carand\u00e1 Bosque, transformou uma agenda oficial em um encontro entre pessoas e prop\u00f3sito. Moradores de Campo Grande participaram da a\u00e7\u00e3o, mostrando que a confer\u00eancia tamb\u00e9m acontece com quem vive a cidade no dia a dia.\u00a0<\/p>\n<p>Foram cerca de 250 mudas de \u00e1rvores nativas do Cerrado e frut\u00edferas plantadas, dando in\u00edcio a um novo espa\u00e7o verde e aproximando a popula\u00e7\u00e3o de um debate que costuma acontecer em n\u00edvel global.\u00a0<\/p>\n<figure class=\"wp-block-image size-large\"><figcaption class=\"wp-element-caption\">Descerramento da placa inaugural do Bosque da COP 15 (Foto: Elias Campos)<\/figcaption><\/figure>\n<p>Entre os participantes, a chefe escoteira Josiane Beraldo destacou o envolvimento dos jovens em a\u00e7\u00f5es pr\u00e1ticas de preserva\u00e7\u00e3o. \u201cQuando a gente traz os jovens para participar de uma a\u00e7\u00e3o como essa, eles deixam de s\u00f3 ouvir falar sobre meio ambiente e passam a fazer parte disso. Plantar uma \u00e1rvore aqui hoje \u00e9 uma forma de mostrar, na pr\u00e1tica, que cada atitude conta e que eles tamb\u00e9m t\u00eam responsabilidade na constru\u00e7\u00e3o de um futuro mais sustent\u00e1vel\u201d, afirma.\u00a0<\/p>\n<p>Jo\u00e3o Davi Sousa, 9 anos, participou do plantio e j\u00e1 sabe da import\u00e2ncia de preservar o meio ambiente \u201cNossa cidade tem muitas aves e elas precisam das \u00e1rvores para se alimentar e tamb\u00e9m descansar. Todos devemos ajudar a preservar o nosso meio ambiente\u201d.<\/p>\n<p>A a\u00e7\u00e3o tamb\u00e9m reuniu participantes de outros pa\u00edses. A coronel de recursos naturais de Benin,\u00a0Gnido\u00a0Assogba, ressaltou a import\u00e2ncia de iniciativas locais com impacto global. \u201cIniciativas como essa s\u00e3o fundamentais para garantir a sa\u00fade dos ecossistemas e a prote\u00e7\u00e3o das esp\u00e9cies migrat\u00f3rias, refor\u00e7ando a import\u00e2ncia da coopera\u00e7\u00e3o entre pa\u00edses\u201d.\u00a0<\/p>\n<figure class=\"wp-block-image size-large\"><figcaption class=\"wp-element-caption\">Secret\u00e1ria-executiva da CMS Amy Fraenkel, ao lado da Prefeita Adriane Lopes, plantando uma muda no Bosque da Cop 15 (Foto: Elias Campos)<\/figcaption><\/figure>\n<p>A secret\u00e1ria-executiva da Conven\u00e7\u00e3o sobre Esp\u00e9cies Migrat\u00f3rias (CMS), Amy\u00a0Fraenkel, refor\u00e7ou que a transforma\u00e7\u00e3o come\u00e7a no territ\u00f3rio. \u201cPlantar \u00e1rvores, preservar habitats e adotar pr\u00e1ticas sustent\u00e1veis no dia a dia s\u00e3o atitudes que conectam as pessoas a um esfor\u00e7o global. O que vemos aqui \u00e9 um exemplo claro de como a\u00e7\u00f5es locais t\u00eam impacto direto na prote\u00e7\u00e3o das esp\u00e9cies e do planeta\u201d.\u00a0<\/p>\n<p>O plantio integra a programa\u00e7\u00e3o da COP15, confer\u00eancia internacional voltada \u00e0 conserva\u00e7\u00e3o das esp\u00e9cies migrat\u00f3rias e \u00e0 biodiversidade. O bosque contribui para a amplia\u00e7\u00e3o da cobertura vegetal urbana e para a cria\u00e7\u00e3o de \u00e1reas de abrigo e alimenta\u00e7\u00e3o para aves migrat\u00f3rias.\u00a0<\/p>\n<p>A prefeita Adriane Lopes destacou que a iniciativa faz parte de uma pol\u00edtica cont\u00ednua de valoriza\u00e7\u00e3o ambiental. \u201cEstamos contribuindo com pol\u00edticas p\u00fablicas efetivas que garantem a continuidade da vida, n\u00e3o apenas das aves migrat\u00f3rias, mas de mais de 400 esp\u00e9cies de aves registradas em Campo Grande. Ao mesmo tempo, deixamos um legado concreto para a cidade\u201d.\u00a0<\/p>\n<p>Presidente da COP15, Jo\u00e3o Paulo Ribeiro Capobianco ressaltou a realiza\u00e7\u00e3o da confer\u00eancia em Campo Grande. \u201cTivemos uma reuni\u00e3o exemplar, com forte participa\u00e7\u00e3o internacional, excelente organiza\u00e7\u00e3o e um ambiente de acolhimento reconhecido pelas delega\u00e7\u00f5es\u201d.\u00a0<\/p>\n<figure class=\"wp-block-image size-large\"><figcaption class=\"wp-element-caption\">Prefeita Adriane Lopes plantando uma muda no Bosque da COP 15 (Foto: Elias Campos)<\/figcaption><\/figure>\n<p>Representando o Governo do Estado, o secret\u00e1rio Jaime\u00a0Verruck\u00a0destacou o trabalho conjunto. \u201cO que entregamos aqui \u00e9 uma confer\u00eancia com alto n\u00edvel t\u00e9cnico e encaminhamentos relevantes para a prote\u00e7\u00e3o das esp\u00e9cies migrat\u00f3rias\u201d.\u00a0<\/p>\n<p>O Bosque da COP15 nasce como um legado que conecta o global ao local, e mostra, na pr\u00e1tica, que o cuidado com o meio ambiente tamb\u00e9m come\u00e7a com a participa\u00e7\u00e3o de cada pessoa.\u00a0<\/p>\n<figure class=\"wp-block-image size-large\"><figcaption class=\"wp-element-caption\">In\u00edcio do plantio das mudas do Bosque da COP 15 (Foto: Elias Campos)<\/figcaption><\/figure>\n<p><em>#ParaTodosVerem: A imagem em destaque mostra a popula\u00e7\u00e3o e participantes da COP 15 plantando \u00e1rvores nativas do Cerrado e frut\u00edferas no Bosque da COP 15<\/em><\/p>\n<\/div>\n<p><script async defer async defer src=\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=1#xfbml=1&amp;version=v3.2\" id=\"prefeitura-campogrande-script-facebook-sdk-js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O plantio do Bosque da COP15, neste s\u00e1bado (28), no Carand\u00e1 Bosque, transformou uma agenda oficial em um encontro entre pessoas e prop\u00f3sito. Moradores de Campo Grande participaram da a\u00e7\u00e3o, mostrando que a confer\u00eancia tamb\u00e9m acontece com quem vive a cidade no dia a dia.\u00a0 Foram cerca de 250 mudas de \u00e1rvores nativas do Cerrado &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,12410,12225,4],"tags":[],"class_list":["post-458154","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-ms","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O plantio do Bosque da COP15, neste s\u00e1bado (28), no Carand\u00e1 Bosque, transformou uma agenda oficial em um encontro entre pessoas e prop\u00f3sito. Moradores de Campo Grande participaram da a\u00e7\u00e3o, mostrando que a confer\u00eancia tamb\u00e9m acontece com quem vive a cidade no dia a dia.\u00a0 Foram cerca de 250 mudas de \u00e1rvores nativas do Cerrado &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-29T03:38:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T11:10:24+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campogrande.ms.gov.br\\\/cgnoticias\\\/noticia\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/03\\\/29\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias\",\"datePublished\":\"2026-03-29T03:38:01+00:00\",\"dateModified\":\"2026-03-30T11:10:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/03\\\/29\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\\\/\"},\"wordCount\":677,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"Mato Grosso do Sul\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campogrande.ms.gov.br\\\/cgnoticias\\\/noticia\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/03\\\/29\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\\\/\",\"url\":\"https:\\\/\\\/www.campogrande.ms.gov.br\\\/cgnoticias\\\/noticia\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15\\\/\",\"name\":\"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2026-03-29T03:38:01+00:00\",\"dateModified\":\"2026-03-30T11:10:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campogrande.ms.gov.br\\\/cgnoticias\\\/noticia\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campogrande.ms.gov.br\\\/cgnoticias\\\/noticia\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campogrande.ms.gov.br\\\/cgnoticias\\\/noticia\\\/populacao-participa-e-da-vida-ao-bosque-da-cop15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/","og_locale":"pt_BR","og_type":"article","og_title":"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias","og_description":"O plantio do Bosque da COP15, neste s\u00e1bado (28), no Carand\u00e1 Bosque, transformou uma agenda oficial em um encontro entre pessoas e prop\u00f3sito. Moradores de Campo Grande participaram da a\u00e7\u00e3o, mostrando que a confer\u00eancia tamb\u00e9m acontece com quem vive a cidade no dia a dia.\u00a0 Foram cerca de 250 mudas de \u00e1rvores nativas do Cerrado &hellip;","og_url":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2026-03-29T03:38:01+00:00","article_modified_time":"2026-03-30T11:10:24+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/03\/29\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias","datePublished":"2026-03-29T03:38:01+00:00","dateModified":"2026-03-30T11:10:24+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/03\/29\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\/"},"wordCount":677,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","Mato Grosso do Sul","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2026\/03\/29\/populacao-participa-e-da-vida-ao-bosque-da-cop15-cgnoticias\/","url":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/","name":"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2026-03-29T03:38:01+00:00","dateModified":"2026-03-30T11:10:24+00:00","breadcrumb":{"@id":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.campogrande.ms.gov.br\/cgnoticias\/noticia\/populacao-participa-e-da-vida-ao-bosque-da-cop15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Popula\u00e7\u00e3o participa e d\u00e1 vida ao Bosque da COP15\u00a0 \u2013 CGNot\u00edcias"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1VbA","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/458154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=458154"}],"version-history":[{"count":1,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/458154\/revisions"}],"predecessor-version":[{"id":458239,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/458154\/revisions\/458239"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=458154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=458154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=458154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}