{"id":461638,"date":"2026-05-30T16:03:24","date_gmt":"2026-05-30T19:03:24","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/30\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\/"},"modified":"2026-05-30T16:03:24","modified_gmt":"2026-05-30T19:03:24","slug":"desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/30\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\/","title":{"rendered":"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p><strong>Os trabalhadores podem usar, desde a \u00faltima\u00a0segunda-feira (25), parte dos recursos dispon\u00edveis do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) para renegociar d\u00edvidas em atraso com bancos e institui\u00e7\u00f5es financeiras no Novo Desenrola Brasil.<\/strong><\/p>\n<p>A modalidade in\u00e9dita de uso do FGTS para colocar as finan\u00e7as em dia tem o objetivo de diminuir os \u00edndices de inadimpl\u00eancia dos trabalhadores no Brasil.<\/p>\n<p><strong>A expectativa do governo federal \u00e9 que o programa de reequil\u00edbrio financeiro movimente at\u00e9 R$ 8,2 bilh\u00f5es em recursos do FGTS<\/strong>, de acordo com\u00a0n\u00fameros informados pelo Minist\u00e9rio do Trabalho e Emprego (MTE).<\/p>\n<p>O Minist\u00e9rio da Fazenda, que coordena o programa, esclarece que <strong>o uso do FGTS suspender\u00e1 temporariamente novos saques anuais e antecipa\u00e7\u00f5es do saque-anivers\u00e1rio at\u00e9 a recomposi\u00e7\u00e3o do saldo.<\/strong><\/p>\n<h2>Quem pode acertar d\u00edvidas<\/h2>\n<p>Chamada tamb\u00e9m de Desenrola 2.0, a iniciativa de renegocia\u00e7\u00e3o \u00e9 destinada a:<\/p>\n<ul>\n<li>Trabalhadores formais com renda mensal de at\u00e9 cinco sal\u00e1rios m\u00ednimos (R$ 8.105, em 2026);<\/li>\n<li>Clientes com d\u00edvidas contratadas at\u00e9 31 de janeiro de 2026 e com atraso entre 91 dias e 720 dias (cerca de dois anos);<\/li>\n<\/ul>\n<p><strong>Entram na lista as d\u00edvidas em atraso com cart\u00e3o de cr\u00e9dito, cheque especial e Cr\u00e9dito Direto ao Consumidor (CDC).<\/strong><\/p>\n<p>Ao entrar no Desenrola,<strong> o trabalhador poder\u00e1 usar at\u00e9 20% do saldo do fundo ou at\u00e9 R$ 1 mil, prevalecendo o maior valor, para amortiza\u00e7\u00e3o (redu\u00e7\u00e3o parcial da d\u00edvida) ou quita\u00e7\u00e3o de d\u00e9bitos em atraso.<\/strong><\/p>\n<p>O saldo do fundo destinado \u00e0 renegocia\u00e7\u00e3o de d\u00edvidas j\u00e1 pode ser consultado no aplicativo do FGTS no Novo Desenrola Brasil.<\/p>\n<p>Contas ativas e inativas do FGTS poder\u00e3o ser usadas pelo trabalhador. Ter\u00e3o prioridade as\u00a0inativas.<\/p>\n<h2>O que o Novo Desenrola Brasil oferece<\/h2>\n<p>Para possibilitar o pagamento parcial ou integral\u00a0das d\u00edvidas atrasadas, o Novo Desenrola Brasil oferece condi\u00e7\u00f5es diferenciadas e mais acess\u00edveis ao trabalhador inadimplente:<\/p>\n<ul>\n<li>Desconto de at\u00e9 90% aplicados sobre o valor da d\u00edvida original;<\/li>\n<li>Taxa m\u00e1xima de juros de 1,99% ao m\u00eas;<\/li>\n<li>Prazo de parcelamento de 12 a 48 vezes;<\/li>\n<li>Consolida\u00e7\u00e3o das d\u00edvidas em uma \u00fanica opera\u00e7\u00e3o.<\/li>\n<\/ul>\n<h2>Como aderir<\/h2>\n<p>De acordo com o Minist\u00e9rio da Fazenda, para aderir ao programa federal, primeiramente, o trabalhador dever\u00e1 autorizar o acesso das institui\u00e7\u00f5es financeiras onde\u00a0tem as d\u00edvidas ao saldo do FGTS para pagar d\u00edvidas, diretamente no aplicativo do FGTS,\u00a0dispon\u00edvel para Android e iOS. \u00c9 preciso fazer <em>login<\/em> com Cadastro de Pessoa F\u00edsica (CPF) e senha da plataforma Gov.br.<\/p>\n<p>Depois da autoriza\u00e7\u00e3o no aplicativo, o trabalhador deve procurar o banco e outras institui\u00e7\u00f5es financeiras nas quais tenha d\u00edvidas e pedir ades\u00e3o ao programa.<\/p>\n<p>Os bancos poder\u00e3o consultar o saldo dispon\u00edvel por at\u00e9 90 dias.<\/p>\n<h2>Renegocia\u00e7\u00e3o da d\u00edvida<\/h2>\n<p><strong>N\u00e3o ser\u00e1 necess\u00e1rio comparecer \u00e0s ag\u00eancias banc\u00e1rias da Caixa para concluir a opera\u00e7\u00e3o.<\/strong><\/p>\n<p>O prazo estimado para formaliza\u00e7\u00e3o <em>online<\/em> da opera\u00e7\u00e3o \u00e9 de at\u00e9 30 dias ap\u00f3s a consulta do saldo dispon\u00edvel.<\/p>\n<p>Ap\u00f3s concretizar a renegocia\u00e7\u00e3o da d\u00edvida, as informa\u00e7\u00f5es ser\u00e3o registradas na Caixa Econ\u00f4mica Federal, respons\u00e1vel por administrar os recursos do fundo.<\/p>\n<p>O banco oficial, ent\u00e3o, far\u00e1 a transfer\u00eancia dos valores diretamente aos bancos respons\u00e1veis pelos contratos.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, Os trabalhadores podem usar, desde a \u00faltima\u00a0segunda-feira (25), parte dos recursos dispon\u00edveis do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) para renegociar d\u00edvidas em atraso com bancos e institui\u00e7\u00f5es financeiras no Novo Desenrola Brasil. A modalidade in\u00e9dita de uso do FGTS para colocar as finan\u00e7as em dia tem o objetivo de diminuir &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,12225,4],"tags":[],"class_list":["post-461638","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso\" \/>\n<meta property=\"og:description\" content=\"Por EBC, Os trabalhadores podem usar, desde a \u00faltima\u00a0segunda-feira (25), parte dos recursos dispon\u00edveis do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) para renegociar d\u00edvidas em atraso com bancos e institui\u00e7\u00f5es financeiras no Novo Desenrola Brasil. A modalidade in\u00e9dita de uso do FGTS para colocar as finan\u00e7as em dia tem o objetivo de diminuir &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-30T19:03:24+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/economia\\\/noticia\\\/2026-05\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/05\\\/30\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso\",\"datePublished\":\"2026-05-30T19:03:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/05\\\/30\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\\\/\"},\"wordCount\":565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/economia\\\/noticia\\\/2026-05\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/05\\\/30\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\\\/\",\"url\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/economia\\\/noticia\\\/2026-05\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\",\"name\":\"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2026-05-30T19:03:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/economia\\\/noticia\\\/2026-05\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/economia\\\/noticia\\\/2026-05\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/economia\\\/noticia\\\/2026-05\\\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso","og_locale":"pt_BR","og_type":"article","og_title":"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso","og_description":"Por EBC, Os trabalhadores podem usar, desde a \u00faltima\u00a0segunda-feira (25), parte dos recursos dispon\u00edveis do Fundo de Garantia do Tempo de Servi\u00e7o (FGTS) para renegociar d\u00edvidas em atraso com bancos e institui\u00e7\u00f5es financeiras no Novo Desenrola Brasil. A modalidade in\u00e9dita de uso do FGTS para colocar as finan\u00e7as em dia tem o objetivo de diminuir &hellip;","og_url":"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2026-05-30T19:03:24+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/30\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso","datePublished":"2026-05-30T19:03:24+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/30\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\/"},"wordCount":565,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/30\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso\/","url":"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso","name":"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2026-05-30T19:03:24+00:00","breadcrumb":{"@id":"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2026-05\/desenrola-brasil-saiba-como-usar-fgts-para-pagar-dividas-em-atraso#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Desenrola Brasil: saiba como usar FGTS para pagar d\u00edvidas em atraso"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1W5M","amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/461638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=461638"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/461638\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=461638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=461638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=461638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}