{"id":461667,"date":"2026-05-31T14:27:27","date_gmt":"2026-05-31T17:27:27","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/31\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\/"},"modified":"2026-05-31T14:27:27","modified_gmt":"2026-05-31T17:27:27","slug":"caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/31\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\/","title":{"rendered":"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p>O julgamento da morte do menino Henry Borel, de 4 anos, entrou\u00a0no s\u00e9timo dia neste domingo (31). No banco dos r\u00e9us est\u00e3o o ex-vereador Jairo Souza Santos e a professora Monique Medeiros, acusados do crime. Eles s\u00e3o o padrasto e m\u00e3e do menino, respectivamente. <strong>O\u00a0Tribunal do J\u00fari come\u00e7ou a ouvir as testemunhas de defesa dos r\u00e9us no s\u00e1bado (30) e continua neste domingo. A sess\u00e3o deve se estender por toda a semana.<\/strong><\/p>\n<p>Presidido pela ju\u00edza Elizabeth Machado Louro, <strong>o j\u00fari, ontem, ouviu o engenheiro Bryan Medeiros da Costa Silva, irm\u00e3o de Monique e\u00a0principal testemunha de defesa dela. <\/strong>Durante mais de 8 horas, ele respondeu a perguntas da ju\u00edza, das defesas e da acusa\u00e7\u00e3o, representada pelo Minist\u00e9rio P\u00fablico do Estado do Rio de Janeiro. <strong>O homem\u00a0fez uma descri\u00e7\u00e3o afetuosa da irm\u00e3, oito anos mais velha, e do conv\u00edvio familiar.<\/strong><\/p>\n<p>Segundo Bryan, Monique era uma m\u00e3e zelosa, que sempre trabalhou e esteve ao lado do ex-marido\u00a0Leniel Borel, pai de Henry, &#8220;nos altos e baixos&#8221; da vida. Ele tamb\u00e9m falou sobre o relacionamento da irm\u00e3 com Jairo. Disse que os dois se conheceram pela internet, que o homem era gentil e nenhum familiar desconfiou de que ele poderia ser autor de agress\u00f5es que levaram o pequeno \u00e0 morte, conforme a den\u00fancia. Monique \u00e9 acusada de tortura e de participa\u00e7\u00e3o no homic\u00eddio.<\/p>\n<p><strong>Bryan tamb\u00e9m relatou que o padrasto de Henry, ap\u00f3s a divulga\u00e7\u00e3o dos laudos relacionando as les\u00f5es no menino a agress\u00f5es,\u00a0tentou persuadir Monique a mentir sobre os fatos que antecederam a morte do garoto.<\/strong> Uma prima, segundo ele, alertou para a possibilidade de Monique estar sendo manipulada, o que fez a fam\u00edlia buscar uma defesa separada da de Jairo.<\/p>\n<p>No julgamento,<strong> o irm\u00e3o afirmou ainda que o filho era prioridade para a r\u00e9 e que ela jamais permitiria qualquer agress\u00e3o a ele.<\/strong><\/p>\n<p>No s\u00e1bado, tamb\u00e9m foram ouvidos um colega de trabalho de Monique, em uma escola, e uma funcion\u00e1ria da brinquedoteca do condom\u00ednio onde ocorreu o crime. A mulher disse que a r\u00e9 frequentava o espa\u00e7o com a crian\u00e7a e era atenciosa.<\/p>\n<p>Na sexta (29), os jurados j\u00e1 tinham ouvido as testemunhas de acusa\u00e7\u00e3o. <strong>O \u00faltimo a depor foi o pai de Henry, Leniel Borel, que terminou de falar \u00e0s 4h15 da madrugada de s\u00e1bado.<\/strong><\/p>\n<p><strong>Segundo o advogado Cristiano Medeiros, assistente da acusa\u00e7\u00e3o, ligada ao pai do menino, o depoimento de Bryan n\u00e3o altera o conjunto de provas do processo.<\/strong> &#8220;Ele n\u00e3o presenciou os fatos e tudo o que afirma saber foi contado por Monique, ap\u00f3s sua pris\u00e3o, quando ela j\u00e1 tinha evidente interesse em construir uma vers\u00e3o defensiva&#8221;, comentou, em nota enviada \u00e0 imprensa na manh\u00e3 deste domingo.<\/p>\n<p>Na avalia\u00e7\u00e3o do assistente, as declara\u00e7\u00f5es n\u00e3o t\u00eam for\u00e7a. No processo, lembra, documentos comprovam que Henry foi lesionado enquanto estava sob os cuidados da m\u00e3e e do padrasto.<\/p>\n<p><strong>A defesa de Jairo argumenta que a lacera\u00e7\u00e3o hep\u00e1tica, que provocou a hemorragia e morte de Henry, conforme o laudo pericial, teria sido provocada pelas sucessivas manobras de ressuscita\u00e7\u00e3o no menino, no hospital. O \u00a0m\u00e9dico-legista Luiz Carlos Leal Preste discordou da tese, no julgamento.<\/strong><\/p>\n<p>Em depoimento, outro legista, <strong>Luiz Airton Saveedra de Paiva afirmou que foram tr\u00eas traumatismos em locais diferentes da cabe\u00e7a.<\/strong> &#8220;A\u00e7\u00f5es essas que resultaram no descolamento do couro cabeludo da v\u00edtima. No t\u00f3rax, h\u00e1 sinais de contus\u00e3o nos pulm\u00f5es e de hemorragia retroa\u00f3rtica e no abd\u00f4men, hemorragia peritoneal, o que foi a causa do \u00f3bito\u201d, apontou.<\/p>\n<p><strong>Saveedra afirmou que Henry estava sem vida quando chegou ao hospital.<\/strong><\/p>\n<p>No depoimento, o delegado do caso Henrique Damasceno, confirmou que Jairo fez press\u00e3o para que a unidade de sa\u00fade atestasse a morte da crian\u00e7a, sem a necessidade de encaminhar o corpo para o Instituto M\u00e9dico Legal (IML), onde seria periciado.<\/p>\n<h2>O caso<\/h2>\n<p>Segundo a den\u00fancia, na madrugada de 8 de mar\u00e7o de 2021, Dr. Jairinho espancou at\u00e9 a morte o menino Henry, enquanto a m\u00e3e, Monique Medeiros, se omitiu da responsabilidade, o que levou ao homic\u00eddio. De acordo com o Minist\u00e9rio P\u00fablico, em outras tr\u00eas ocasi\u00f5es em fevereiro de 2021, Jairo tinha submetido o menino a sofrimento f\u00edsico e mental com emprego de viol\u00eancia.<\/p>\n<p>Jairo \u00e9 acusado de\u00a0homic\u00eddio qualificado por meio cruel que impossibilitou a defesa da v\u00edtima;\u00a0tr\u00eas torturas praticadas contra crian\u00e7a; fraude processual; coa\u00e7\u00e3o no curso do processo, entre outros crimes. Monique responde por sete crimes, entre eles homic\u00eddio por omiss\u00e3o qualificado e omiss\u00e3o.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, O julgamento da morte do menino Henry Borel, de 4 anos, entrou\u00a0no s\u00e9timo dia neste domingo (31). No banco dos r\u00e9us est\u00e3o o ex-vereador Jairo Souza Santos e a professora Monique Medeiros, acusados do crime. Eles s\u00e3o o padrasto e m\u00e3e do menino, respectivamente. O\u00a0Tribunal do J\u00fari come\u00e7ou a ouvir as testemunhas de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,12225,4],"tags":[],"class_list":["post-461667","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia\" \/>\n<meta property=\"og:description\" content=\"Por EBC, O julgamento da morte do menino Henry Borel, de 4 anos, entrou\u00a0no s\u00e9timo dia neste domingo (31). No banco dos r\u00e9us est\u00e3o o ex-vereador Jairo Souza Santos e a professora Monique Medeiros, acusados do crime. Eles s\u00e3o o padrasto e m\u00e3e do menino, respectivamente. O\u00a0Tribunal do J\u00fari come\u00e7ou a ouvir as testemunhas de &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-31T17:27:27+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/justica\\\/noticia\\\/2026-05\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/05\\\/31\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia\",\"datePublished\":\"2026-05-31T17:27:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/05\\\/31\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\\\/\"},\"wordCount\":818,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/justica\\\/noticia\\\/2026-05\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/05\\\/31\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\\\/\",\"url\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/justica\\\/noticia\\\/2026-05\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\",\"name\":\"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2026-05-31T17:27:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/justica\\\/noticia\\\/2026-05\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/justica\\\/noticia\\\/2026-05\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/justica\\\/noticia\\\/2026-05\\\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia","og_locale":"pt_BR","og_type":"article","og_title":"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia","og_description":"Por EBC, O julgamento da morte do menino Henry Borel, de 4 anos, entrou\u00a0no s\u00e9timo dia neste domingo (31). No banco dos r\u00e9us est\u00e3o o ex-vereador Jairo Souza Santos e a professora Monique Medeiros, acusados do crime. Eles s\u00e3o o padrasto e m\u00e3e do menino, respectivamente. O\u00a0Tribunal do J\u00fari come\u00e7ou a ouvir as testemunhas de &hellip;","og_url":"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2026-05-31T17:27:27+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/31\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia","datePublished":"2026-05-31T17:27:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/31\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\/"},"wordCount":818,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2026\/05\/31\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia\/","url":"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia","name":"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2026-05-31T17:27:27+00:00","breadcrumb":{"@id":"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-05\/caso-henry-borel-julgamento-de-jairinho-e-monique-entra-no-setimo-dia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Caso Henry Borel: julgamento de Jairinho e Monique entra no s\u00e9timo dia"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1W6f","amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/461667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=461667"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/461667\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=461667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=461667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=461667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}