{"id":463691,"date":"2026-07-14T09:43:11","date_gmt":"2026-07-14T12:43:11","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\/"},"modified":"2026-07-14T09:43:11","modified_gmt":"2026-07-14T12:43:11","slug":"reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\/","title":{"rendered":"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol"},"content":{"rendered":"<p>Por EBC, <\/p>\n<div>\n<p>V\u00eddeos nas redes sociais mostram a sele\u00e7\u00e3o francesa de futebol treinando em clima de descontra\u00e7\u00e3o antes de enfrentar a Espanha, em uma das semifinais da Copa do Mundo 2026. A disputa ocorrer\u00e1 nesta ter\u00e7a-feira (14), nos Estados Unidos, e definir\u00e1 um dos finalistas do mundial.<\/p>\n<p><strong>Fora de campo, entretanto, jogadores e autoridades dos dois pa\u00edses se unem com seriedade para repudiar declara\u00e7\u00f5es racistas contra\u00a0&#8220;Les Blues&#8221;, apelido da sele\u00e7\u00e3o francesa de futebol<\/strong>.<\/p>\n<p>O time e jogadores t\u00eam sido alvo de coment\u00e1rios discriminat\u00f3rios ao longo do torneio. No domingo (11), veio \u00e0 tona artigo do ex-primeiro-ministro espanhol Mariano Rajoy, no poder entre 2011 e 2018, afirmando que a Fran\u00e7a tem um &#8220;plantel de alt\u00edssimo n\u00edvel&#8221;, mas sem franceses. Ele fazia refer\u00eancia depreciativa \u00e0 presen\u00e7a de jogadores descendentes de imigrantes, oriundos, principalmente, de antigas col\u00f4nias na \u00c1frica, o que reflete a diversidade \u00e9tnica da sociedade francesa.<\/p>\n<p>O coment\u00e1rio de Rajoy foi rebatido tanto por jogadores espanh\u00f3is, como Pau Cubars\u00ed e Borja Iglesias, quanto pelo atual primeiro-ministro da Espanha, Pedro S\u00e1nchez. Em sua conta em rede social, Sanch\u00e9z disse que a afirma\u00e7\u00e3o do antecessor era uma vergonha e declarou: &#8220;que ven\u00e7a o melhor e que perca o racismo&#8221;.<\/p>\n<p>O diretor-executivo do Observat\u00f3rio da Discrimina\u00e7\u00e3o Racial no Futebol, organiza\u00e7\u00e3o da sociedade civil brasileira, Marcelo Carvalho, disse que os coment\u00e1rios refletem o pensamento de grupos sociais alinhados \u00e0 extrema-direita.<\/p>\n<p>&#8220;O momento pol\u00edtico do Brasil e do mundo, com ascens\u00e3o da extrema-direita, faz com que as\u00a0pessoas se sintam mais confiantes para expressar o racismo&#8221;, avaliou Carvalho, que tamb\u00e9m acredita que a sensa\u00e7\u00e3o de anonimato das pessoas na internet contribui para os ataques. &#8220;Elas\u00a0acreditam que n\u00e3o ser\u00e3o encontradas&#8221;.<\/p>\n<h2>Aumento de ataques racistas<\/h2>\n<p><strong>Durante esta Copa, a Federa\u00e7\u00e3o Internacional de Futebol (Fifa) revelou ter identificado aumento expressivo de ataques racistas<\/strong>. Na primeira fase, foram 89 mil publica\u00e7\u00f5es abusivas nas redes, n\u00famero 13 vezes maior do que na Copa de 2022, sendo 11% de car\u00e1ter racial, mais do que o identificado na Copa de 2022.<\/p>\n<p>Acompanhando os casos no torneio, Carvalho ressalta que a pr\u00f3pria Fifa tem adotado medidas para controlar os atos. Desde o in\u00edcio da competi\u00e7\u00e3o, lembra o especialista, dois jogadores \u2500 um do Paraguai e outro do Equador \u2500 foram expulsos gra\u00e7as ao Protocolo Vini Jr.\u00a0de combate ao racismo. Eles taparam a boca com as m\u00e3os ao discutirem dentro de campo, o que foi proibido para impedir a oculta\u00e7\u00e3o de provas.<\/p>\n<p>&#8220;Antes, era a palavra de um contra a de outro, e a v\u00edtima sa\u00eda prejudicada&#8221;, disse.<\/p>\n<p>Agora, al\u00e9m do apoio dos jogadores, h\u00e1 o das federa\u00e7\u00f5es e de autoridades, o que, na vis\u00e3o do especialista, &#8220;\u00e9 um movimento que transforma tanto o futebol como a sociedade&#8221;.<\/p>\n<blockquote>\n<p>&#8220;Vimos in\u00fameros atletas sofrendo racismo depois do Vini, mas que n\u00e3o se calaram, denunciaram, porque o Vin\u00edcius mostrou um caminho, tanto ele, quanto o [Kylian] Mbapp\u00e9, que sempre se posicionou&#8221;, citou. &#8220;Quando a Federa\u00e7\u00e3o Francesa de Futebol e o governo franc\u00eas saem em defesa do Mbapp\u00e9, est\u00e3o saindo em defesa de todas as pessoas negras e isso est\u00e1 muito al\u00e9m do futebol&#8221;, completou o diretor.<\/p>\n<\/blockquote>\n<p>Antes de Rajoy atacar a sele\u00e7\u00e3o francesa\u00a0de futebol, a senadora paraguaia Celeste Amarilla\u00a0dirigiu pesados insultos racistas a Mbapp\u00e9, logo ap\u00f3s a derrota do Paraguai para o time europeu.<\/p>\n<p>Ela foi rebatida pelo pr\u00f3prio Mbapp\u00e9, que disse que a pol\u00edtica\u00a0\u00e9 indigna da posi\u00e7\u00e3o de representante dos paraguaios no parlamento. O jogador\u00a0recebeu apoio tanto da Federa\u00e7\u00e3o Francesa de Futebol\u00a0quanto das autoridades de seu pa\u00eds.<\/p>\n<p>&#8220;As declara\u00e7\u00f5es racistas feitas pela senadora paraguaia Celeste Amarilla contra Kylian Mbapp\u00e9 s\u00e3o absolutamente desprez\u00edveis e inaceit\u00e1veis&#8221;, disse a federa\u00e7\u00e3o, que acionou a Procuradoria francesa.<\/p>\n<p>O \u00f3rg\u00e3o abriu um inqu\u00e9rito por inj\u00faria agravada e incita\u00e7\u00e3o ao \u00f3dio e \u00e0 viol\u00eancia. &#8220;Como algu\u00e9m pode proferir tais palavras? Essas declara\u00e7\u00f5es s\u00e3o criminosas e repreens\u00edveis&#8221;, completou a federa\u00e7\u00e3o.<\/p>\n<p>\u00a0&#8220;N\u00e3o estamos mais deixando os casos &#8216;passarem batido'&#8221;, finalizou o diretor do Observat\u00f3rio.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por EBC, V\u00eddeos nas redes sociais mostram a sele\u00e7\u00e3o francesa de futebol treinando em clima de descontra\u00e7\u00e3o antes de enfrentar a Espanha, em uma das semifinais da Copa do Mundo 2026. A disputa ocorrer\u00e1 nesta ter\u00e7a-feira (14), nos Estados Unidos, e definir\u00e1 um dos finalistas do mundial. Fora de campo, entretanto, jogadores e autoridades dos &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,12225,4],"tags":[],"class_list":["post-463691","post","type-post","status-publish","format-standard","hentry","category-entretenimento","category-noticias","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol\" \/>\n<meta property=\"og:description\" content=\"Por EBC, V\u00eddeos nas redes sociais mostram a sele\u00e7\u00e3o francesa de futebol treinando em clima de descontra\u00e7\u00e3o antes de enfrentar a Espanha, em uma das semifinais da Copa do Mundo 2026. A disputa ocorrer\u00e1 nesta ter\u00e7a-feira (14), nos Estados Unidos, e definir\u00e1 um dos finalistas do mundial. Fora de campo, entretanto, jogadores e autoridades dos &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T12:43:11+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol\",\"datePublished\":\"2026-07-14T12:43:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\\\/\"},\"wordCount\":720,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ENTRETENIMENTO\",\"NOTICIAS\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\\\/\",\"url\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\",\"name\":\"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2026-07-14T12:43:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol","og_locale":"pt_BR","og_type":"article","og_title":"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol","og_description":"Por EBC, V\u00eddeos nas redes sociais mostram a sele\u00e7\u00e3o francesa de futebol treinando em clima de descontra\u00e7\u00e3o antes de enfrentar a Espanha, em uma das semifinais da Copa do Mundo 2026. A disputa ocorrer\u00e1 nesta ter\u00e7a-feira (14), nos Estados Unidos, e definir\u00e1 um dos finalistas do mundial. Fora de campo, entretanto, jogadores e autoridades dos &hellip;","og_url":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2026-07-14T12:43:11+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol","datePublished":"2026-07-14T12:43:11+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\/"},"wordCount":720,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ENTRETENIMENTO","NOTICIAS","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/14\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol\/","url":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol","name":"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2026-07-14T12:43:11+00:00","breadcrumb":{"@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/reacao-ao-racismo-contra-jogadores-negros-na-copa-vai-alem-do-futebol#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Rea\u00e7\u00e3o ao racismo contra jogadores negros na Copa vai al\u00e9m do futebol"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1WCT","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/463691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=463691"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/463691\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=463691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=463691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=463691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}