{"id":463751,"date":"2026-07-15T00:47:50","date_gmt":"2026-07-15T03:47:50","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\/"},"modified":"2026-07-15T00:47:50","modified_gmt":"2026-07-15T03:47:50","slug":"jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\/","title":{"rendered":"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos"},"content":{"rendered":"<p><\/p>\n<div>\n<p>O clima de Copa do Mundo estar\u00e1 presente no \u00faltimo dia dos Jogos Parasul-Americanos, que acontecem em Valledupar (Col\u00f4mbia). Nesta quarta-feira (15), a partir das 18h (hor\u00e1rio de Bras\u00edlia), o cl\u00e1ssico entre Brasil e Argentina decidir\u00e1 o campe\u00e3o do futebol de cegos. O evento tem<strong> transmiss\u00e3o ao vivo<\/strong> no canal do YouTube da Se\u00f1al Col\u00f4mbia, emissora p\u00fablica local.\u00a0<\/p>\n<p>O Brasil ainda n\u00e3o foi vazado na competi\u00e7\u00e3o e ganhou quatro dos cinco jogos da primeira fase, que reuniu seis pa\u00edses e foi disputada em turno \u00fanico. O \u00faltimo triunfo foi sobre o Peru, por 5 a 0, na \u00faltima segunda-feira (13), em Agust\u00edn Codazzi, cidade a cerca de 62 quil\u00f4metros de Valledupar.<\/p>\n<p>A equipe verde e amarela bateu Chile e Col\u00f4mbia, ambos por 1 a 0, al\u00e9m de golear o Panam\u00e1 por incr\u00edveis 18 a 0 na estreia. A \u00fanica partida sem triunfo foi justamente contra a Argentina: empate sem gols pela terceira rodada.<\/p>\n<p>A rivalidade entre brasileiros e argentinos no futebol de campo \u00e9 ainda mais acirrada na vers\u00e3o adaptada para atletas com defici\u00eancia visual. Tratam-se das \u00fanicas sele\u00e7\u00f5es a conquistarem as oito edi\u00e7\u00f5es j\u00e1 realizadas do Campeonato Mundial. Cinco finais foram justamente entre os dois pa\u00edses. O Brasil levou a melhor em quatro (1998, 2000, 2014 e 2018), perdendo apenas em 2006.<\/p>\n<p>A sele\u00e7\u00e3o verde e amarela \u00e9 a maior vencedora do Mundial, com cinco t\u00edtulos, o \u00faltimo justamente contra os\u00a0hermanos, em 2018, em Madri (Espanha). Os argentinos, porem, s\u00e3o os atuais campe\u00f5es. Na edi\u00e7\u00e3o de 2023, em Birmingham (Reino Unido), eles venceram a China, que tinha eliminado os brasileiros na semifinal.<\/p>\n<p>Antes dos Jogos Parasul-Americanos, Brasil e Argentina n\u00e3o se enfrentavam desde que ambas decidiram vaga \u00e0 final da Paralimp\u00edada de Paris (Fran\u00e7a), em 2024. Ap\u00f3s o empate sem gols no tempo normal, os\u00a0hermanos\u00a0venceram nos p\u00eanaltis por 4 a 3. Cinco vezes medalhistas de ouro, os brasileiros ca\u00edram na semifinal paral\u00edmpica do futebol de cegos pela primeira vez.<\/p>\n<p>A \u00faltima final entre as duas equipes foi a da Copa Am\u00e9rica de 2022, em C\u00f3rdoba (Argentina). Os donos da casa levaram a melhor nas penalidades, por 2 a 1, depois de as redes n\u00e3o balan\u00e7arem durante o tempo normal.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"pt\" xml:lang=\"pt\">Os Jogos Parasul-Americanos de Valledupar est\u00e3o chegando ao fim, mas o Brasil segue no topo! \ud83c\udde7\ud83c\uddf7\ud83d\udd1d<\/p>\n<p>No 12\u00ba dia de competi\u00e7\u00f5es, os brasileiros subiram ao p\u00f3dio 41 vezes para alcan\u00e7ar as 161 medalhas na competi\u00e7\u00e3o. \ud83e\udd47\ud83e\udd48\ud83e\udd49<\/p>\n<p>Confira os resultados dos brasileiros nas provas da nata\u00e7\u00e3o,\u2026 <a href=\"https:\/\/t.co\/vtBTLe3T4N\">pic.twitter.com\/vtBTLe3T4N<\/a><\/p>\n<p>\u2014 Comit\u00ea Paral\u00edmpico Brasileiro (@BraParalimpico) July 14, 2026<\/p><\/blockquote>\n<h2>Mais que centen\u00e1ria<\/h2>\n<p>A campanha do Brasil nos Jogos Parasul-Americanos segue dominante. A \u00faltima segunda foi o dia que a delega\u00e7\u00e3o mais obteve medalhas desde o come\u00e7o do evento, h\u00e1 11 dias. Foram 41 p\u00f3dios, sendo 13 com brasileiro no topo, al\u00e9m de 17 pratas e 11 bronzes.<\/p>\n<p>A delega\u00e7\u00e3o verde e amarela encerrou a segunda com 161 medalhas no total: 70 douradas, 57 prateadas e 34 bronzeadas. S\u00e3o 21 ouros a mais que a anfitri\u00e3 Col\u00f4mbia, segunda colocada no quadro. Na compara\u00e7\u00e3o com o \u00faltimo domingo (12), a novidade foi Argentina (21 topos de p\u00f3dio) e Venezuela (16) ultrapassarem o Chile, que estava em terceiro.<\/p>\n<p>O atletismo foi a modalidade que mais rendeu medalhas ao Brasil na segunda. Das 19 arrematadas nas provas de pistas e de campo, foram seis de ouro, sete de prata e seis de bronze. Destaque para a dobradinha feminina nos 400 metros da classe T12 (baixa vis\u00e3o), com vit\u00f3ria da capixaba Lorraine Aguiar, seguida pela rondoniense Ketyla Teodoro.<\/p>\n<p>Tamb\u00e9m houve dobradinha nos 100 metros livre da nata\u00e7\u00e3o na classe S14 (defici\u00eancia intelectual), com a mineira Ana Karolina Soares levando o ouro e a paulista Stephanie Ariodante ficando com a prata. A modalidade rendeu 14 medalhas ao Brasil na segunda.<\/p>\n<p>Na bocha, que re\u00fane esportistas com paralisia cerebral severa ou les\u00f5es medulares, os brasileiros conquistaram dois ouros, ambos no feminino. Pela classe BC2 (atletas que conseguem arremessar sem aux\u00edlio), a vit\u00f3ria foi da cearense Clarice Sobreira. J\u00e1 a paulista D\u00e9bora Bargas foi a campe\u00e3 na classe BC3 (utilizam instrumentos para fazer as jogadas, como uma calha, e contam com o aux\u00edlio de um assistente sem defici\u00eancia, chamado calheiro).<\/p>\n<p>Outro ouro veio no tiro com arco, na disputa por equipes mistas da classe W1 (atletas com defici\u00eancias graves em bra\u00e7os e pernas). A parceria ganhadora foi formada pela paranaense Juliana da Silva e pelo cearense Eug\u00eanio Franco &#8211; que foi o representante brasileiro mais velho nos Jogos de Paris, aos 64 anos.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O clima de Copa do Mundo estar\u00e1 presente no \u00faltimo dia dos Jogos Parasul-Americanos, que acontecem em Valledupar (Col\u00f4mbia). Nesta quarta-feira (15), a partir das 18h (hor\u00e1rio de Bras\u00edlia), o cl\u00e1ssico entre Brasil e Argentina decidir\u00e1 o campe\u00e3o do futebol de cegos. O evento tem transmiss\u00e3o ao vivo no canal do YouTube da Se\u00f1al Col\u00f4mbia, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3,4587,4],"tags":[],"class_list":["post-463751","post","type-post","status-publish","format-standard","hentry","category-esportes1","category-esportes","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos\" \/>\n<meta property=\"og:description\" content=\"O clima de Copa do Mundo estar\u00e1 presente no \u00faltimo dia dos Jogos Parasul-Americanos, que acontecem em Valledupar (Col\u00f4mbia). Nesta quarta-feira (15), a partir das 18h (hor\u00e1rio de Bras\u00edlia), o cl\u00e1ssico entre Brasil e Argentina decidir\u00e1 o campe\u00e3o do futebol de cegos. O evento tem transmiss\u00e3o ao vivo no canal do YouTube da Se\u00f1al Col\u00f4mbia, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T03:47:50+00:00\" \/>\n<meta name=\"author\" content=\"MR News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MR News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\\\/\"},\"author\":{\"name\":\"MR News\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\"},\"headline\":\"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos\",\"datePublished\":\"2026-07-15T03:47:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\\\/\"},\"wordCount\":776,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ESPORTES\",\"Esportes\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/07\\\/15\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\\\/\",\"url\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\",\"name\":\"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2026-07-15T03:47:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-07\\\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/MRNewslogo2.png\",\"width\":223,\"height\":58,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/be3203154562a9f207407861cef7827b\",\"name\":\"MR News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g\",\"caption\":\"MR News\"},\"description\":\"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr\",\"sameAs\":[\"HUGO R.\",\"Admin\"],\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos","og_locale":"pt_BR","og_type":"article","og_title":"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos","og_description":"O clima de Copa do Mundo estar\u00e1 presente no \u00faltimo dia dos Jogos Parasul-Americanos, que acontecem em Valledupar (Col\u00f4mbia). Nesta quarta-feira (15), a partir das 18h (hor\u00e1rio de Bras\u00edlia), o cl\u00e1ssico entre Brasil e Argentina decidir\u00e1 o campe\u00e3o do futebol de cegos. O evento tem transmiss\u00e3o ao vivo no canal do YouTube da Se\u00f1al Col\u00f4mbia, &hellip;","og_url":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2026-07-15T03:47:50+00:00","author":"MR News","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"MR News","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\/"},"author":{"name":"MR News","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b"},"headline":"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos","datePublished":"2026-07-15T03:47:50+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\/"},"wordCount":776,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ESPORTES","Esportes","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2026\/07\/15\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos\/","url":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos","name":"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2026-07-15T03:47:50+00:00","breadcrumb":{"@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-07\/jogos-parasul-americanos-brasil-e-argentina-decidem-futebol-de-cegos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Jogos Parasul-Americanos: Brasil e Argentina decidem futebol de cegos"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2019\/06\/MRNewslogo2.png","width":223,"height":58,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/be3203154562a9f207407861cef7827b","name":"MR News","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04084e6d73c042b8646e7c17b494073bf0ede3ea13c7105cfc45cbbbc28385a4?s=96&d=monsterid&r=g","caption":"MR News"},"description":"Especializado em jornalismo colaborativo pela FTP em n\u00edvel de p\u00f3s-gradua\u00e7\u00e3o. suporte@oimeliga.combr","sameAs":["HUGO R.","Admin"],"url":"https:\/\/mrnews.com.br\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1WDR","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/463751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=463751"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/463751\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=463751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=463751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=463751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}