{"id":466083,"date":"2026-09-02T18:57:46","date_gmt":"2026-09-02T21:57:46","guid":{"rendered":"https:\/\/mrnews.com.br\/index.php\/2026\/09\/02\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\/"},"modified":"2026-09-02T18:57:46","modified_gmt":"2026-09-02T21:57:46","slug":"selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro","status":"publish","type":"post","link":"https:\/\/mrnews.com.br\/index.php\/2026\/09\/02\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\/","title":{"rendered":"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A primeira convoca\u00e7\u00e3o da sele\u00e7\u00e3o brasileira p\u00f3s-Copa do Mundo est\u00e1 programada para a pr\u00f3xima quarta-feira (9), a partir das 15h (hor\u00e1rio de Bras\u00edlia). A data foi confirmada hoje pela CBF. O t\u00e9cnico italiano Carlo Ancelotti anunciar\u00e1 os 26 jogadores que enfrentar\u00e3o Austr\u00e1lia e \u00cdndia em tr\u00eas amistosos fora do pa\u00eds na pr\u00f3xima Data Fifa (entre 21 de setembro e 6 de outubro). Os jogos ser\u00e3o os primeiros do ciclo de prepara\u00e7\u00e3o para o Mundial de 2030, com sedes em Espanha, Portugal, Marrocos, Uruguai, Argentina e Paraguai.<\/p>\n<p>Ancelotti divulgar\u00e1 a lista de convocados na sede da CBF, no Rio de Janeiro, com <strong>transmiss\u00e3o ao vivo<\/strong> na CBF TV, no YouTube. \u00c9 grande a expectativa em torno da primeira lista do t\u00e9cnico italiano ap\u00f3s a <strong>elimina\u00e7\u00e3o precoce do Brasil para a Noruega,<\/strong> nas oitavas de final do Mundial deste ano. Al\u00e9m de acompanhar os jogos no pa\u00eds, o treinador passou a \u00faltima semana na Europa, acompanhando jogos com atletas brasileiros que defendem clubes franceses e ingleses. \u00a0<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"pt\" xml:lang=\"pt\">A Super Data FIFA vem a\u00ed! \ud83c\udde7\ud83c\uddf7\ud83d\udc9b<\/p>\n<p>Na pr\u00f3xima quarta-feira, 9 de Setembro, \u00e0s 15h (de Bras\u00edlia), teremos a divulga\u00e7\u00e3o dos 26 nomes que disputar\u00e3o os tr\u00eas amistosos que fazem parte da agenda da Sele\u00e7\u00e3o nos meses de setembro e outubro.<\/p>\n<p>25\/09 \u2022 \ud83c\udde6\ud83c\uddfavs\ud83c\udde7\ud83c\uddf7<br \/>29\/09 \u2022 \ud83c\udde6\ud83c\uddfavs\ud83c\udde7\ud83c\uddf7<br \/>03\/10 \u2022 \ud83c\uddee\ud83c\uddf3vs\ud83c\udde7\ud83c\uddf7\u2026 <a href=\"https:\/\/t.co\/8xu6MMmj5g\">pic.twitter.com\/8xu6MMmj5g<\/a><\/p>\n<p>\u2014 brasil (@CBF_Futebol) September 2, 2026<\/p><\/blockquote>\n<p>O Brasil enfrentar\u00e1 a Austr\u00e1lia duas vezes na casa dos advers\u00e1rios. O primeiro confronto ser\u00e1 em 25 de setembro (uma sexta-feira), \u00e0s 7h (hor\u00e1rio de Bras\u00edlia), no est\u00e1dio Queensland Country Bank, em Townsville. Quatro dias depois, as duas sele\u00e7\u00f5es voltam a duelar, no mesmo hor\u00e1rio, no est\u00e1dio Suncorp, em Brisbane. J\u00e1 a partida contra a \u00cdndia est\u00e1 programada para 3 de outubro (um s\u00e1bado), \u00e0s 11h, no est\u00e1dio Salt Lake, em Calcut\u00e1.<\/p>\n<p>      <!-- Relacionada --><\/p>\n<p>            <!-- Relacionada -->\n    <\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A primeira convoca\u00e7\u00e3o da sele\u00e7\u00e3o brasileira p\u00f3s-Copa do Mundo est\u00e1 programada para a pr\u00f3xima quarta-feira (9), a partir das 15h (hor\u00e1rio de Bras\u00edlia). A data foi confirmada hoje pela CBF. O t\u00e9cnico italiano Carlo Ancelotti anunciar\u00e1 os 26 jogadores que enfrentar\u00e3o Austr\u00e1lia e \u00cdndia em tr\u00eas amistosos fora do pa\u00eds na pr\u00f3xima Data Fifa (entre &hellip;<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3,4587,4],"tags":[],"class_list":["post-466083","post","type-post","status-publish","format-standard","hentry","category-esportes1","category-esportes","category-servicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro\" \/>\n<meta property=\"og:description\" content=\"A primeira convoca\u00e7\u00e3o da sele\u00e7\u00e3o brasileira p\u00f3s-Copa do Mundo est\u00e1 programada para a pr\u00f3xima quarta-feira (9), a partir das 15h (hor\u00e1rio de Bras\u00edlia). A data foi confirmada hoje pela CBF. O t\u00e9cnico italiano Carlo Ancelotti anunciar\u00e1 os 26 jogadores que enfrentar\u00e3o Austr\u00e1lia e \u00cdndia em tr\u00eas amistosos fora do pa\u00eds na pr\u00f3xima Data Fifa (entre &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\" \/>\n<meta property=\"og:site_name\" content=\"MRNews\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T21:57:46+00:00\" \/>\n<meta name=\"author\" content=\"Fernando Corraa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conspirou\" \/>\n<meta name=\"twitter:site\" content=\"@conspirou\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Corraa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-09\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/09\\\/02\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\\\/\"},\"author\":{\"name\":\"Fernando Corraa\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/2f073f2d87903a2ff9a065e41bbf17d4\"},\"headline\":\"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro\",\"datePublished\":\"2026-09-02T21:57:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/09\\\/02\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\\\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"articleSection\":[\"ESPORTES\",\"Esportes\",\"SERVI\u00c7OS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-09\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/2026\\\/09\\\/02\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\\\/\",\"url\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-09\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\",\"name\":\"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\"},\"datePublished\":\"2026-09-02T21:57:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-09\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-09\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenciabrasil.ebc.com.br\\\/esportes\\\/noticia\\\/2026-09\\\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/mrnews.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#website\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"name\":\"MRNews\",\"description\":\"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB\",\"publisher\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mrnews.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#organization\",\"name\":\"MRNews\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"contentUrl\":\"https:\\\/\\\/mrnews.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/MRNEws.png\",\"width\":1254,\"height\":1254,\"caption\":\"MRNews\"},\"image\":{\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eaipahpah\\\/?locale2=pt_BR\",\"https:\\\/\\\/x.com\\\/conspirou\",\"https:\\\/\\\/www.instagram.com\\\/eai_pahpah\",\"https:\\\/\\\/br.pinterest.com\\\/mrnewsn\\\/boards\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mrnews.com.br\\\/#\\\/schema\\\/person\\\/2f073f2d87903a2ff9a065e41bbf17d4\",\"name\":\"Fernando Corraa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9069acb0e588c9f4346ba747284aef18a5faaab575e89e9ccc64e315003f0b82?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9069acb0e588c9f4346ba747284aef18a5faaab575e89e9ccc64e315003f0b82?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9069acb0e588c9f4346ba747284aef18a5faaab575e89e9ccc64e315003f0b82?s=96&d=monsterid&r=g\",\"caption\":\"Fernando Corraa\"},\"url\":\"https:\\\/\\\/mrnews.com.br\\\/index.php\\\/author\\\/fernando-corraa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro","og_locale":"pt_BR","og_type":"article","og_title":"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro","og_description":"A primeira convoca\u00e7\u00e3o da sele\u00e7\u00e3o brasileira p\u00f3s-Copa do Mundo est\u00e1 programada para a pr\u00f3xima quarta-feira (9), a partir das 15h (hor\u00e1rio de Bras\u00edlia). A data foi confirmada hoje pela CBF. O t\u00e9cnico italiano Carlo Ancelotti anunciar\u00e1 os 26 jogadores que enfrentar\u00e3o Austr\u00e1lia e \u00cdndia em tr\u00eas amistosos fora do pa\u00eds na pr\u00f3xima Data Fifa (entre &hellip;","og_url":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro","og_site_name":"MRNews","article_publisher":"https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","article_published_time":"2026-09-02T21:57:46+00:00","author":"Fernando Corraa","twitter_card":"summary_large_image","twitter_creator":"@conspirou","twitter_site":"@conspirou","twitter_misc":{"Escrito por":"Fernando Corraa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#article","isPartOf":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/09\/02\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\/"},"author":{"name":"Fernando Corraa","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/2f073f2d87903a2ff9a065e41bbf17d4"},"headline":"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro","datePublished":"2026-09-02T21:57:46+00:00","mainEntityOfPage":{"@id":"https:\/\/mrnews.com.br\/index.php\/2026\/09\/02\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"articleSection":["ESPORTES","Esportes","SERVI\u00c7OS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrnews.com.br\/index.php\/2026\/09\/02\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro\/","url":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro","name":"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro","isPartOf":{"@id":"https:\/\/mrnews.com.br\/#website"},"datePublished":"2026-09-02T21:57:46+00:00","breadcrumb":{"@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2026-09\/selecao-brasileira-tera-1a-convocacao-pos-copa-em-9-de-setembro#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mrnews.com.br\/"},{"@type":"ListItem","position":2,"name":"Sele\u00e7\u00e3o brasileira ter\u00e1 1\u00aa convoca\u00e7\u00e3o p\u00f3s-Copa em 9 de setembro"}]},{"@type":"WebSite","@id":"https:\/\/mrnews.com.br\/#website","url":"https:\/\/mrnews.com.br\/","name":"MRNews","description":"MRNews Jogos de hoje da TV, transmiss\u00f5es ao vivo, Not\u00edcias de futebol, Jogos ao vivo, Lives, resumo de novelas, Programa\u00e7\u00e3o da Globo, A Fazenda e BBB","publisher":{"@id":"https:\/\/mrnews.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mrnews.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/mrnews.com.br\/#organization","name":"MRNews","url":"https:\/\/mrnews.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","contentUrl":"https:\/\/mrnews.com.br\/wp-content\/uploads\/2026\/08\/MRNEws.png","width":1254,"height":1254,"caption":"MRNews"},"image":{"@id":"https:\/\/mrnews.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eaipahpah\/?locale2=pt_BR","https:\/\/x.com\/conspirou","https:\/\/www.instagram.com\/eai_pahpah","https:\/\/br.pinterest.com\/mrnewsn\/boards\/","https:\/\/www.youtube.com\/channel\/UCacgnpznQ61fifLWr1tQ-vA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/mrnews.com.br\/#\/schema\/person\/2f073f2d87903a2ff9a065e41bbf17d4","name":"Fernando Corraa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/9069acb0e588c9f4346ba747284aef18a5faaab575e89e9ccc64e315003f0b82?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9069acb0e588c9f4346ba747284aef18a5faaab575e89e9ccc64e315003f0b82?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9069acb0e588c9f4346ba747284aef18a5faaab575e89e9ccc64e315003f0b82?s=96&d=monsterid&r=g","caption":"Fernando Corraa"},"url":"https:\/\/mrnews.com.br\/index.php\/author\/fernando-corraa\/"}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa2Qf7-1Xft","amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/466083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=466083"}],"version-history":[{"count":0,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/466083\/revisions"}],"wp:attachment":[{"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=466083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=466083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrnews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=466083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}